{"id":13118,"date":"2018-04-25T16:21:51","date_gmt":"2018-04-25T19:21:51","guid":{"rendered":"http:\/\/beatforbeat.com.br\/site\/?p=13118"},"modified":"2019-05-10T19:59:22","modified_gmt":"2019-05-10T22:59:22","slug":"entrevistamos-seeb","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/","title":{"rendered":"Entrevistamos: Seeb"},"content":{"rendered":"<p>Nomeados ao Grammy e com um EP que acabou de ser lan\u00e7ado, conversamos com o trio Seeb, que nos falou sobre o novo material, planos futuros e muito mais.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-13119 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit.jpg\" alt=\"Seeb\" width=\"630\" height=\"433\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit.jpg 2500w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit-300x206.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit-768x527.jpg 768w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit-1024x703.jpg 1024w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/433;\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Com um \u00e1lbum lan\u00e7ado recentemente (que voc\u00ea pode ouvir abaixo enquanto l\u00ea essa entrevista), conversamos com <em>Espen<\/em>, do trio <strong>Seeb<\/strong>, que nos contou sobre o processo de cria\u00e7\u00e3o do grupo, o Grammy, planos futuros e muito mais. Aperte o play e venha com a gente&#8230; Entrevistamos: Seeb!<\/p><div id=\"beatf-2096917019\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p style=\"text-align: center;\">(To read this interview in english, click <a href=\"https:\/\/beatforbeat.com.br\/site\/interview-seeb\/\">here<\/a>)<\/p>\n<p><center><iframe data-src=\"https:\/\/open.spotify.com\/embed\/album\/6ERbVmi33M9tKn7RNtt17G\" width=\"300\" height=\"380\" frameborder=\"0\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/center><\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: justify;\"><strong>Beat for Beat<\/strong> &#8211; Ei pessoal, muito obrigado por aceitarem uma entrevista com o Beat for Beat! Vamos come\u00e7ar no passado um pouquinho, muito clich\u00ea: qual \u00e9 a sensa\u00e7\u00e3o de serem nomeados ao Grammy??<br \/>\n<strong>Seeb<\/strong> &#8211; Foi um acontecimento muito legal. Tecnicamente, foi Mike (autor da m\u00fasica) o indicado, isso porque nos EUA, o remix n\u00e3o conta como uma vers\u00e3o da m\u00fasica, apenas o original. Mas de qualquer forma, foi o remix que se tornou um sucesso e a raz\u00e3o da indica\u00e7\u00e3o, ent\u00e3o foi \u00f3timo. N\u00f3s tamb\u00e9m est\u00e1vamos l\u00e1, na premia\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; Voc\u00eas s\u00e3o da Noruega, como \u00e9 a cena eletr\u00f4nica por l\u00e1? Como foi sair de toda aquela maravilha n\u00f3rdica e vir para o calor dos pa\u00edses do Sul? Preferem o clima mais quente ou o gelo \u00e9 o amado por voc\u00eas?<br \/>\n<strong>Seeb<\/strong> &#8211; N\u00f3s preferimos os dois climas, na verdade. O inverno aqui em cima pode ser maravilhoso, mas depois de alguns meses, sempre come\u00e7amos a desejar o calor e o ver\u00e3o. Eu acho que somos influenciados por isso na m\u00fasica tamb\u00e9m. N\u00e3o gostariamos de morar em um lugar onde o clima n\u00e3o mudasse durante o ano. J\u00e1 cena da m\u00fasica eletr\u00f4nica na Noruega est\u00e1 indo muito bem atualmente, com artistas como Kygo, Alan Walker, Matoma, Astrid S e Sigrid. Muitos artistas mainstream e um monte de artistas mais undergrounds e t\u00e3o empolgantes quanto.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/19748622_1704283456543644_2015775066058266489_n.png\"><img decoding=\"async\" class=\"aligncenter wp-image-13121 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/19748622_1704283456543644_2015775066058266489_n.png\" alt=\"Seeb\" width=\"630\" height=\"505\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/19748622_1704283456543644_2015775066058266489_n.png 960w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/19748622_1704283456543644_2015775066058266489_n-300x240.png 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/19748622_1704283456543644_2015775066058266489_n-768x615.png 768w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/505;\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; Podemos dizer que voc\u00eas s\u00e3o da &#8220;nova safra&#8221; de artistas, j\u00e1 que Simen e Espen lan\u00e7aram seus primeiros remixes em 2015. N\u00e3o \u00e9 intimidante tentar entrar numa cena que \u00e9 dominada por gigantes em todo lugar?<br \/>\n<strong>Seeb<\/strong> &#8211; Sim! Foi e ficamos muito assustados no come\u00e7o. Conhecer grandes nomes e pessoas que n\u00f3s respeit\u00e1vamos h\u00e1 muito tempo, nos deixava bem nervosos, mas logo aprendemos a n\u00e3o pensar muito nisso e apenas se concentrar em criar m\u00fasica, n\u00e3o t\u00e3o influenciada por quem fez a m\u00fasica original&#8230; Tamb\u00e9m nos sentimos intimidados desde que surgimos do nada e conseguimos cuidar de um nicho para n\u00f3s mesmos, desde o come\u00e7o. N\u00f3s n\u00e3o tivemos que percorrer o mesmo longo caminho que muitos DJs tiveram que fazer antes de n\u00f3s, j\u00e1 que viemos do mundo dos produtores e, de v\u00e1rias maneiras, nos preparamos para isso h\u00e1 muito tempo.<\/p>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; Voc\u00eas j\u00e1 trabalharam com Shawn Mendes, Coldplay, One Republic, Skylar Grey&#8230; que artista \u00e9 o grande sonho de voc\u00eas, para uma colabora\u00e7\u00e3o?<br \/>\n<strong>Seeb<\/strong> &#8211; Sim, o ruim \u00e9 que \u00e0s vezes, temos que trabalhar via Skype, por exemplo. Nem sempre voc\u00ea tem a chance sentar juntos com outros artistas em um est\u00fadio, j\u00e1 que as pessoas est\u00e3o sempre muito ocupadas na ind\u00fastria musical, ent\u00e3o tentamos nos adaptar a isso. Nosso artista dos sonhos agora, s\u00e3o a <em>Dua Lipa<\/em> e <em>Post Malone<\/em>. Acho que podemos fazer coisas bacanas com eles.<\/p>\n<p><iframe title=\"Coldplay - Hymn For The Weekend [Seeb Remix] (Official Audio)\" width=\"1200\" height=\"675\" data-src=\"https:\/\/www.youtube.com\/embed\/k1gsZ-OsGpI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; Inicialmente um duo e depois, um trio com a entrada de Niklas. Isso mudou a rela\u00e7\u00e3o de voc\u00eas, do projeto ou da sonoridade que possuem?<br \/>\n<strong>Seeb<\/strong> &#8211; Na verdade, n\u00e3o. N\u00f3s ainda trabalhamos no est\u00fadio como sempre fizemos e virar um trio ajudou a tornar as coisas ainda mais f\u00e1ceis de se fazer e claro, \u00e9 muito animador ter mais ouvidos. N\u00f3s sentimos que nos complementamos.<\/p>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; &#8216;Nice To Meet You&#8217; \u00e9 um EP que \u00e9 uma forma de agradecimento a todos que apoiaram o projeto. Podemos esperar um \u00e1lbum logo?<br \/>\n<strong>Seeb<\/strong> &#8211; N\u00f3s, realmente, n\u00e3o somos pessoas que fazem \u00e1lbuns, mas acabou que come\u00e7armos a brincar com a ideia de montar um, ent\u00e3o, vamos ver em um futuro pr\u00f3ximo o que acontece.<\/p>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; Qual foi o processo criativo para o EP? S\u00e3o 3 cabe\u00e7as pensando, n\u00e3o houve muito conflito na hora da composi\u00e7\u00e3o?<br \/>\n<strong>Seeb<\/strong> &#8211; \u00c9 sempre um conflito, e n\u00e3o tem como contornar isso, por\u00e9m isso tamb\u00e9m funciona como uma din\u00e2mica dentro do Seeb. A faixa come\u00e7a, tipicamente, com uma ideia do Simen ou de mim mesmo (Espen) e ent\u00e3o, come\u00e7a uma batalha pra ver quem consegue os melhores ganchos ou acordes. Trabalhamos assim h\u00e1 mais de 15 anos e \u00e9 dif\u00edcil mudar, mas assim que chegamos num acordo comum, as coisas se juntam e acontecem muito r\u00e1pido. Niklas \u00e9 mais como um negociador durante esses processos.<\/p>\n<figure id=\"attachment_13123\" aria-describedby=\"caption-attachment-13123\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/29595161_1811294715842517_8698707439225801919_n.jpg\"><img decoding=\"async\" class=\"wp-image-13123 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/29595161_1811294715842517_8698707439225801919_n.jpg\" alt=\"Seeb Dagny\" width=\"630\" height=\"630\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/29595161_1811294715842517_8698707439225801919_n.jpg 960w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/29595161_1811294715842517_8698707439225801919_n-150x150.jpg 150w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/29595161_1811294715842517_8698707439225801919_n-300x300.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/29595161_1811294715842517_8698707439225801919_n-768x768.jpg 768w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/29595161_1811294715842517_8698707439225801919_n-144x144.jpg 144w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/630;\" \/><\/a><figcaption id=\"caption-attachment-13123\" class=\"wp-caption-text\">Seeb e Dagny, que d\u00e1 voz ao single Drink About<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; O rato deadmau5, por exemplo, sempre diz que sobram m\u00fasicas que ele n\u00e3o consegue colocar em seus \u00e1lbuns. Sobrou muita coisa de voc\u00eas e que pretendem lan\u00e7ar como singles sozinhos?<br \/>\n<strong>Seeb<\/strong> &#8211; Temos muitas m\u00fasicas inacabadas por a\u00ed, literalmente centenas e n\u00f3s, simplesmente, n\u00e3o podemos trabalhar em tudo. Claro, existem alguns projetos favoritos que n\u00e3o se encaixam aqui e ali, mas podem aparecer como singles um dia. Uma coisa boa sobre o Seeb \u00e9 que podemos decidir, por n\u00f3s mesmos, o que gostar\u00edamos de lan\u00e7ar. Antes, quando est\u00e1vamos trabalhando apenas como produtores, havia muita opini\u00e3o de outras pessoas, o tempo todo, o que n\u00e3o acontece mais hoje.<\/p>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; \u00c1sia, Estados Unidos, Europa&#8230; qual o objetivo a ser alcan\u00e7ado pelo Seeb? E o Brasil?<br \/>\n<strong>Seeb<\/strong> &#8211; Esperamos que o novo single, Drink About, seja o hino de ver\u00e3o de 2018, ser\u00e1? Ou talvez, dev\u00eassemos esperar at\u00e9 o inverno daqui, j\u00e1 que estamos em lados opostos do equador e passa-lo nas praias do Rio? Isso seria muito legal! N\u00f3s, definitivamente, gostar\u00edamos de fazer mais shows ou festivais no Brasil. Sabemos que temos muitos f\u00e3s l\u00e1 e em v\u00e1rios outros pa\u00edses da Am\u00e9rica do Sul, ent\u00e3o, estamos colocando em nossa lista de poss\u00edveis destinos para 2018!<\/p>\n<figure id=\"attachment_13120\" aria-describedby=\"caption-attachment-13120\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/seeb-indonesia.jpg\"><img decoding=\"async\" class=\"wp-image-13120 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/seeb-indonesia.jpg\" alt=\"Seeb Indonesia\" width=\"630\" height=\"421\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/seeb-indonesia.jpg 958w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/seeb-indonesia-300x200.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/seeb-indonesia-768x513.jpg 768w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/421;\" \/><\/a><figcaption id=\"caption-attachment-13120\" class=\"wp-caption-text\">Seeb na Indonesia<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; De 2002, quando Simen e Espen se conheceram, at\u00e9 hoje, o que mudou de muito importante na vida pessoal de voc\u00eas e o que esperam para os pr\u00f3ximos, 5 anos, talvez?<br \/>\n<strong>Seeb<\/strong> &#8211; Isso \u00e9 muito tempo atr\u00e1s, hein?! Muitas coisas mudaram. N\u00f3s dois tivemos um monte de filhos e hoje, temos mais foco e liberdade agora realmente nos concentrar em fazer m\u00fasica. O sucesso tamb\u00e9m possibilitou a divulga\u00e7\u00e3o da nossa m\u00fasica por todo o mundo e somos eternamente gratos por isso, pelas pessoas que tiveram tempo para ouvi-la. Certamente, mudou as nossas vidas e todos os nossos familiares para melhor.<\/p>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; Por fim, O que podemos esperar do Seeb, como um conjunto, para o resto de 2018? Alguma surpresa que possam compartilhar?<br \/>\n<strong>Seeb<\/strong> &#8211; N\u00e3o neste momento, rs. Estamos pensando em um monte de novas collabs e projetos, afinal, mesmo fazendo shows, estaremos ao \u201cmesmo tempo\u201d em est\u00fadio, preparando mais e mais coisas tracks. Fiquem ligados!<\/p>\n<p style=\"text-align: justify;\"><strong>B4B<\/strong> &#8211; Muito obrigado Seeb, estamos ansiosos por poder assistir\/ouvir um show ao vivo em terras brasileiras!<br \/>\n<strong>Seeb<\/strong> &#8211; Obrigado!!<\/p>\n","protected":false},"excerpt":{"rendered":"Nomeados ao Grammy e com um EP que acabou de ser lan\u00e7ado, conversamos com o trio Seeb, que&hellip;","protected":false},"author":2,"featured_media":13124,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[18,11],"tags":[2091,2092,2090,749,2093,2089,2094,21],"class_list":{"0":"post-13118","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entrevista","8":"category-thumb","9":"tag-coldplay","10":"tag-dagny","11":"tag-drink-about","12":"tag-grammy","13":"tag-nice-to-meet-you","14":"tag-seeb","15":"tag-skylar-grey","16":"tag-spotify","17":"cs-entry","18":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrevistamos: Seeb<\/title>\n<meta name=\"description\" content=\"Nomeados ao Grammy e com um EP que acabou de ser lan\u00e7ado, conversamos com o trio SEEB, que nos falou sobre o o novo material, planos futuros e muito mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevistamos: Seeb\" \/>\n<meta property=\"og:description\" content=\"Nomeados ao Grammy e com um EP que acabou de ser lan\u00e7ado, conversamos com o trio SEEB, que nos falou sobre o o novo material, planos futuros e muito mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-25T19:21:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-10T22:59:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"Entrevistamos: Seeb\",\"datePublished\":\"2018-04-25T19:21:51+00:00\",\"dateModified\":\"2019-05-10T22:59:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/\"},\"wordCount\":1311,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/IMG_9472-Edit-1.jpg\",\"keywords\":[\"Coldplay\",\"Dagny\",\"Drink About\",\"Grammy\",\"Nice To Meet You\",\"Seeb\",\"Skylar Grey\",\"spotify\"],\"articleSection\":[\"Entrevista\",\"Thumb\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/\",\"name\":\"Entrevistamos: Seeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/IMG_9472-Edit-1.jpg\",\"datePublished\":\"2018-04-25T19:21:51+00:00\",\"dateModified\":\"2019-05-10T22:59:22+00:00\",\"description\":\"Nomeados ao Grammy e com um EP que acabou de ser lan\u00e7ado, conversamos com o trio SEEB, que nos falou sobre o o novo material, planos futuros e muito mais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/IMG_9472-Edit-1.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/IMG_9472-Edit-1.jpg\",\"width\":760,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/entrevistamos-seeb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevistamos: Seeb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevistamos: Seeb","description":"Nomeados ao Grammy e com um EP que acabou de ser lan\u00e7ado, conversamos com o trio SEEB, que nos falou sobre o o novo material, planos futuros e muito mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/","og_locale":"pt_BR","og_type":"article","og_title":"Entrevistamos: Seeb","og_description":"Nomeados ao Grammy e com um EP que acabou de ser lan\u00e7ado, conversamos com o trio SEEB, que nos falou sobre o o novo material, planos futuros e muito mais.","og_url":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2018-04-25T19:21:51+00:00","article_modified_time":"2019-05-10T22:59:22+00:00","og_image":[{"width":760,"height":440,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit-1.jpg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"Entrevistamos: Seeb","datePublished":"2018-04-25T19:21:51+00:00","dateModified":"2019-05-10T22:59:22+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/"},"wordCount":1311,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit-1.jpg","keywords":["Coldplay","Dagny","Drink About","Grammy","Nice To Meet You","Seeb","Skylar Grey","spotify"],"articleSection":["Entrevista","Thumb"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/","url":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/","name":"Entrevistamos: Seeb","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit-1.jpg","datePublished":"2018-04-25T19:21:51+00:00","dateModified":"2019-05-10T22:59:22+00:00","description":"Nomeados ao Grammy e com um EP que acabou de ser lan\u00e7ado, conversamos com o trio SEEB, que nos falou sobre o o novo material, planos futuros e muito mais.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit-1.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/04\/IMG_9472-Edit-1.jpg","width":760,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/entrevistamos-seeb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Entrevistamos: Seeb"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/13118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=13118"}],"version-history":[{"count":0,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/13118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/13124"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=13118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=13118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=13118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}