{"id":13491,"date":"2018-05-16T18:21:22","date_gmt":"2018-05-16T21:21:22","guid":{"rendered":"http:\/\/beatforbeat.com.br\/site\/?p=13491"},"modified":"2018-05-16T18:21:22","modified_gmt":"2018-05-16T21:21:22","slug":"aimec-inaugura-sede-europa","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/","title":{"rendered":"AIMEC inaugura sua primeira sede na Europa"},"content":{"rendered":"<p>A AIMEC, escola de m\u00fasica eletr\u00f4nica brasileira, abre sua primeira sede na Europa e torna-se a primeira escola internacional de m\u00fasica eletr\u00f4nica de Portugal.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-capa_novasede_post.png\"><img decoding=\"async\" class=\"aligncenter wp-image-13492 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-capa_novasede_post.png\" alt=\"AIMEC\" width=\"630\" height=\"270\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-capa_novasede_post.png 900w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-capa_novasede_post-300x128.png 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-capa_novasede_post-768x329.png 768w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/270;\" \/><br \/>\n<\/a>Especializada no ensino e educa\u00e7\u00e3o para DJs e Produtores Musicais, a escola que j\u00e1 \u00e9 sucesso no Brasil estar\u00e1 se instalando em terras portuguesas neste m\u00eas de Maio, em Lisboa, com toda a estrutura e m\u00e9todo de ensino que j\u00e1 s\u00e3o reconhecidos no Brasil. Com a miss\u00e3o de formar novos profissionais e consumidores no universo da m\u00fasica, ela estar\u00e1 levando do Brasil toda a sua diversidade, criatividade e cultura musical.<\/p><div id=\"beatf-1114733088\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p style=\"text-align: justify;\">Na <strong>AIMEC Lisboa<\/strong>, voc\u00ea encontrar\u00e1 n\u00e3o apenas um lugar onde vai aprender t\u00e9cnicas e tirar d\u00favidas, mas tamb\u00e9m um local onde voc\u00ea vai poder estabelecer contatos com outros artistas para a constru\u00e7\u00e3o de projetos e redes de relacionamento. No time de professores j\u00e1 contamos com alguns nomes selecionados. DJ Handerson (Brasil) e DJ Nokin (Portugal). Mais professores estar\u00e3o sendo anunciados em breve.<\/p>\n<figure id=\"attachment_13493\" aria-describedby=\"caption-attachment-13493\" style=\"width: 495px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-LISBOA.jpg\"><img decoding=\"async\" class=\"size-full wp-image-13493 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-LISBOA.jpg\" alt=\"AIMEC LISBOA\" width=\"495\" height=\"495\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-LISBOA.jpg 495w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-LISBOA-150x150.jpg 150w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-LISBOA-300x300.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/AIMEC-LISBOA-144x144.jpg 144w\" data-sizes=\"(max-width: 495px) 100vw, 495px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 495px; --smush-placeholder-aspect-ratio: 495\/495;\" \/><\/a><figcaption id=\"caption-attachment-13493\" class=\"wp-caption-text\">Sede da AIMEC em Lisboa<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Sobre a AIMEC <\/strong><\/p>\n<p style=\"text-align: justify;\">A AIMEC iniciou as suas opera\u00e7\u00f5es em 2004 em Curitiba &#8211; Brasil. Nos anos seguintes expandiu para as cidades de Balne\u00e1rio Cambori\u00fa, Campinas e Porto Alegre. Posteriormente abrindo sedes em Joinville, Florian\u00f3polis e Maring\u00e1. Milhares de alunos passam pelas AIMECs no Brasil todos os anos. Al\u00e9m das atividades em salas de aula, a AIMEC organiza competi\u00e7\u00f5es, workshops, palestras, festas e demais eventos.<\/p>\n<p style=\"text-align: justify;\">Em Lisboa estaremos oferecendo os cursos de DJ, Produ\u00e7\u00e3o Musical, Produ\u00e7\u00e3o Musical Avan\u00e7ada, Teoria Musical e Mixagem e Masteriza\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">As matr\u00edculas j\u00e1 est\u00e3o abertas e podem ser feitas atrav\u00e9s do contato: lisboa@aimec.pt. Garanta j\u00e1 a sua vaga com 20% de desconto. Envie uma inbox na p\u00e1gina da escola clicando <a href=\"https:\/\/www.facebook.com\/aimecportugal\/\" target=\"_blank\" rel=\"noopener\">aqui<\/a> e pe\u00e7a o seu!<\/p>\n<p><strong>Informa\u00e7\u00f5es:<br \/>\nAIMEC LISBOA<\/strong><br \/>\nTelefone: 00351 213860213<br \/>\nCelular: 00351 9682323<br \/>\nEndere\u00e7o Edif\u00edcio Castil &#8211; Rua Castilho, 39 &#8211; 12\u00ba andar &#8211; Lisboa \u2013 Portugal<br \/>\nHor\u00e1rio: 10h \u00e0s 13h e das 14:30 \u00e0s 19h.<br \/>\n<a href=\"http:\/\/www.facebook.com\/aimecportugal\" target=\"_blank\" rel=\"noopener\">www.facebook.com\/aimecportugal<\/a><br \/>\n<a href=\"http:\/\/www.instagram.com\/aimecportugal\" target=\"_blank\" rel=\"noopener\">www.instagram.com\/aimecportugal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"A AIMEC, escola de m\u00fasica eletr\u00f4nica brasileira, abre sua primeira sede na Europa e torna-se a primeira escola&hellip;","protected":false},"author":2,"featured_media":13494,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[3],"tags":[563,2255,1541,2136,2251,2252,2253,2258,2133,2254,1714,2256,2257],"class_list":["post-13491","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mainstage","tag-aimec","tag-balneario-camboriu","tag-campinas","tag-curso-dj","tag-dj-handerson","tag-dj-nokin","tag-lisboa","tag-masterizacao","tag-mixagem","tag-porto-alegre","tag-producao-musical","tag-producao-musical-avancada","tag-teoria-musical","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AIMEC inaugura sua primeira sede na Europa<\/title>\n<meta name=\"description\" content=\"A AIMEC, escola de m\u00fasica eletr\u00f4nica, abre sua primeira sede na Europa e torna-se a primeira escola internacional de m\u00fasica eletr\u00f4nica de Portugal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AIMEC inaugura sua primeira sede na Europa\" \/>\n<meta property=\"og:description\" content=\"A AIMEC, escola de m\u00fasica eletr\u00f4nica, abre sua primeira sede na Europa e torna-se a primeira escola internacional de m\u00fasica eletr\u00f4nica de Portugal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-16T21:21:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/aimec.png\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"AIMEC inaugura sua primeira sede na Europa\",\"datePublished\":\"2018-05-16T21:21:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/\"},\"wordCount\":359,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/aimec.png\",\"keywords\":[\"Aimec\",\"Balne\u00e1rio Cambori\u00fa\",\"Campinas\",\"Curso DJ\",\"DJ Handerson\",\"DJ Nokin\",\"Lisboa\",\"Masteriza\u00e7\u00e3o\",\"Mixagem\",\"Porto Alegre\",\"produ\u00e7\u00e3o musical\",\"Produ\u00e7\u00e3o Musical Avan\u00e7ada\",\"Teoria Musical\"],\"articleSection\":[\"Mainstage\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/\",\"name\":\"AIMEC inaugura sua primeira sede na Europa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/aimec.png\",\"datePublished\":\"2018-05-16T21:21:22+00:00\",\"description\":\"A AIMEC, escola de m\u00fasica eletr\u00f4nica, abre sua primeira sede na Europa e torna-se a primeira escola internacional de m\u00fasica eletr\u00f4nica de Portugal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/aimec.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/aimec.png\",\"width\":760,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aimec-inaugura-sede-europa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AIMEC inaugura sua primeira sede na Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AIMEC inaugura sua primeira sede na Europa","description":"A AIMEC, escola de m\u00fasica eletr\u00f4nica, abre sua primeira sede na Europa e torna-se a primeira escola internacional de m\u00fasica eletr\u00f4nica de Portugal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/","og_locale":"pt_BR","og_type":"article","og_title":"AIMEC inaugura sua primeira sede na Europa","og_description":"A AIMEC, escola de m\u00fasica eletr\u00f4nica, abre sua primeira sede na Europa e torna-se a primeira escola internacional de m\u00fasica eletr\u00f4nica de Portugal.","og_url":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2018-05-16T21:21:22+00:00","og_image":[{"width":760,"height":440,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/aimec.png","type":"image\/png"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"AIMEC inaugura sua primeira sede na Europa","datePublished":"2018-05-16T21:21:22+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/"},"wordCount":359,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/aimec.png","keywords":["Aimec","Balne\u00e1rio Cambori\u00fa","Campinas","Curso DJ","DJ Handerson","DJ Nokin","Lisboa","Masteriza\u00e7\u00e3o","Mixagem","Porto Alegre","produ\u00e7\u00e3o musical","Produ\u00e7\u00e3o Musical Avan\u00e7ada","Teoria Musical"],"articleSection":["Mainstage"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/","url":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/","name":"AIMEC inaugura sua primeira sede na Europa","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/aimec.png","datePublished":"2018-05-16T21:21:22+00:00","description":"A AIMEC, escola de m\u00fasica eletr\u00f4nica, abre sua primeira sede na Europa e torna-se a primeira escola internacional de m\u00fasica eletr\u00f4nica de Portugal.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/aimec.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/05\/aimec.png","width":760,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/aimec-inaugura-sede-europa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"AIMEC inaugura sua primeira sede na Europa"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/13491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=13491"}],"version-history":[{"count":0,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/13491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/13494"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=13491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=13491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=13491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}