{"id":14657,"date":"2018-07-25T00:42:45","date_gmt":"2018-07-25T03:42:45","guid":{"rendered":"http:\/\/beatforbeat.com.br\/site\/?p=14657"},"modified":"2018-07-26T02:04:02","modified_gmt":"2018-07-26T05:04:02","slug":"laroc-programacao-diynamic","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/","title":{"rendered":"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival"},"content":{"rendered":"<p>Entre os convocados da primeira edi\u00e7\u00e3o do Diynamic Festival no Laroc est\u00e3o Solomun, Magdalena, Lehar, HOSH e Kolletiv Turmstrasse.<!--more--><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-1.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-14658 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-1.jpg\" alt=\"Diynamic\" width=\"630\" height=\"354\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-1.jpg 960w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-1-300x169.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-1-768x432.jpg 768w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/354;\" \/><\/a><\/p>\n<p>Neste \u00faltimo m\u00eas, ap\u00f3s o sucesso da estreia da <em>Elrow<\/em>, recebemos a surpresa que o <strong><em>Diynamic Festival<\/em><\/strong>, evento organizado pela label de <em>Solomun<\/em>, desembarcar\u00e1 pela primeira vez no Brasil no <em>Laroc<\/em>, querido club dos brasileiros localizado em Valinhos, interior de S\u00e3o Paulo, no dia 27 de outubro.<\/p><div id=\"beatf-1764877872\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Ontem, o pr\u00f3prio\u00a0selo\u00a0em parceria com a casa noturna lan\u00e7ou a programa\u00e7\u00e3o completa, com <em>Lehar, Karmon, Magdalena, Kolletiv Turmstrasse, HOSH<\/em> e o pr\u00f3prio <em>Solomun<\/em>. Confira o line up abaixo:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-festival.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-14659 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-festival.jpg\" alt=\"Diynamic\" width=\"630\" height=\"630\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-festival.jpg 960w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-festival-150x150.jpg 150w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-festival-300x300.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-festival-768x768.jpg 768w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/diynamic-festival-144x144.jpg 144w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/630;\" \/><\/a><\/p>\n<p>Os ingressos\u00a0come\u00e7am a ser vendidos nesta pr\u00f3xima sexta feira, 27 de Outubro. Para maiores informa\u00e7\u00f5es acesse o <a href=\"https:\/\/www.laroc.club\" target=\"_blank\" rel=\"noopener\">site<\/a> do <em>Laroc<\/em>\u00a0ou o evento oficial no <a href=\"https:\/\/www.facebook.com\/events\/788431638032589\/\" target=\"_blank\" rel=\"noopener\"><em>Facebook<\/em><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Entre os convocados da primeira edi\u00e7\u00e3o do Diynamic Festival no Laroc est\u00e3o Solomun, Magdalena, Lehar, HOSH e Kolletiv&hellip;","protected":false},"author":1,"featured_media":14660,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[9,3],"tags":[91,424,379,2651,35,255,364,285,49],"class_list":{"0":"post-14657","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaque","8":"category-mainstage","9":"tag-91","10":"tag-brasil","11":"tag-club","12":"tag-diynamic","13":"tag-festival","14":"tag-laroc","15":"tag-sao-paulo","16":"tag-solomun","17":"tag-techno","18":"cs-entry","19":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival<\/title>\n<meta name=\"description\" content=\"Entre os convocados da primeira edi\u00e7\u00e3o do Diynamic Festival no Laroc est\u00e3o Solomun, Magdalena, Lehar, HOSH e Kolletiv Turmstrasse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival\" \/>\n<meta property=\"og:description\" content=\"Entre os convocados da primeira edi\u00e7\u00e3o do Diynamic Festival no Laroc est\u00e3o Solomun, Magdalena, Lehar, HOSH e Kolletiv Turmstrasse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-25T03:42:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-26T05:04:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/Laroc-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/4dbf95c5732c4cdf103571d9769155ae\"},\"headline\":\"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival\",\"datePublished\":\"2018-07-25T03:42:45+00:00\",\"dateModified\":\"2018-07-26T05:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/\"},\"wordCount\":140,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Laroc-1-1.jpg\",\"keywords\":[\"2018\",\"Brasil\",\"Club\",\"Diynamic\",\"festival\",\"Laroc\",\"S\u00e3o Paulo\",\"Solomun\",\"Techno\"],\"articleSection\":[\"Destaque\",\"Mainstage\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/\",\"name\":\"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Laroc-1-1.jpg\",\"datePublished\":\"2018-07-25T03:42:45+00:00\",\"dateModified\":\"2018-07-26T05:04:02+00:00\",\"description\":\"Entre os convocados da primeira edi\u00e7\u00e3o do Diynamic Festival no Laroc est\u00e3o Solomun, Magdalena, Lehar, HOSH e Kolletiv Turmstrasse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Laroc-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Laroc-1-1.jpg\",\"width\":760,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/laroc-programacao-diynamic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/4dbf95c5732c4cdf103571d9769155ae\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival","description":"Entre os convocados da primeira edi\u00e7\u00e3o do Diynamic Festival no Laroc est\u00e3o Solomun, Magdalena, Lehar, HOSH e Kolletiv Turmstrasse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/","og_locale":"pt_BR","og_type":"article","og_title":"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival","og_description":"Entre os convocados da primeira edi\u00e7\u00e3o do Diynamic Festival no Laroc est\u00e3o Solomun, Magdalena, Lehar, HOSH e Kolletiv Turmstrasse.","og_url":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/","og_site_name":"Beat for Beat","article_published_time":"2018-07-25T03:42:45+00:00","article_modified_time":"2018-07-26T05:04:02+00:00","og_image":[{"width":760,"height":440,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/Laroc-1-1.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/4dbf95c5732c4cdf103571d9769155ae"},"headline":"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival","datePublished":"2018-07-25T03:42:45+00:00","dateModified":"2018-07-26T05:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/"},"wordCount":140,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/Laroc-1-1.jpg","keywords":["2018","Brasil","Club","Diynamic","festival","Laroc","S\u00e3o Paulo","Solomun","Techno"],"articleSection":["Destaque","Mainstage"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/","url":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/","name":"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/Laroc-1-1.jpg","datePublished":"2018-07-25T03:42:45+00:00","dateModified":"2018-07-26T05:04:02+00:00","description":"Entre os convocados da primeira edi\u00e7\u00e3o do Diynamic Festival no Laroc est\u00e3o Solomun, Magdalena, Lehar, HOSH e Kolletiv Turmstrasse.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/Laroc-1-1.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2018\/07\/Laroc-1-1.jpg","width":760,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/laroc-programacao-diynamic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Laroc anuncia programa\u00e7\u00e3o do Diynamic Festival"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/4dbf95c5732c4cdf103571d9769155ae","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/beatforbeat.com.br\/site\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/14657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=14657"}],"version-history":[{"count":0,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/14657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/14660"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=14657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=14657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=14657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}