{"id":19252,"date":"2019-07-26T19:19:36","date_gmt":"2019-07-26T22:19:36","guid":{"rendered":"http:\/\/beatforbeat.com.br\/site\/?p=19252"},"modified":"2019-08-05T02:00:05","modified_gmt":"2019-08-05T05:00:05","slug":"ultra-retorno-bayfront-park","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/","title":{"rendered":"Ultra Music Festival confirma seu retorno ao Bayfront Park"},"content":{"rendered":"<p>Em uma decis\u00e3o inesperada, a cidade de Miami votou a favor e o Ultra Music Festival retorna ao Bayfront Park para sua edi\u00e7\u00e3o 2020. Entenda:<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/07\/Ultra-e1564179208239.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-19253 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/07\/Ultra-e1564179208239.jpg\" alt=\"Ultra\" width=\"630\" height=\"402\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/07\/Ultra-e1564179208239.jpg 830w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/07\/Ultra-e1564179208239-300x192.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/07\/Ultra-e1564179208239-768x490.jpg 768w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/402;\" \/><\/a><\/p>\n<p>Uma das maiores novelas da m\u00fasica eletr\u00f4nica do \u00faltimo ano, parece finalmente chegar ao sim. Ap\u00f3s grandes incertezas, mudan\u00e7a de local, especula\u00e7\u00f5es e rumores, eis que o <strong>Ultra Music Festival<\/strong> anunciou seu t\u00e3o aguardado retorno ao <strong>Beyfront Park<\/strong>, sua tradicioal casa no cora\u00e7\u00e3o de Miami.<\/p><div id=\"beatf-125418479\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Tudo come\u00e7ou em setembro de 2018, quando o Ultra perdeu <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/beatforbeat.com.br\/site\/ultra-miami-perde-direitos-bayfront-park\/\" target=\"_blank\" rel=\"noopener noreferrer\">os direitos de uso do Bayfront Park<\/a><\/span>. Ap\u00f3s anos sendo realizado no Bayfront, o Ultra se viu desolado, sem sua casa t\u00e3o amada e a partir de ent\u00e3o, come\u00e7ou a procura por um novo local. Em novembro daquele mesmo ano, a organiza\u00e7\u00e3o do evento divulgou ent\u00e3o, o espa\u00e7o escolhido para a edi\u00e7\u00e3o 2019 do evento: <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/beatforbeat.com.br\/site\/confirmado-ultra-virgina-key\/\" target=\"_blank\" rel=\"noopener noreferrer\">Virginia Key<\/a><\/span>.<\/p>\n<p>Entre confus\u00f5es envolvendo outro festival que era realizado no mesmo lugar (e na mesma \u00e9poca) o <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/beatforbeat.com.br\/site\/rapture-festival-entra-na-justica-contra-ultra-miami\/\" target=\"_blank\" rel=\"noopener noreferrer\">Rapture<\/a><\/span>, uma intensa campanha de divulga\u00e7\u00e3o do espa\u00e7o, que incluiu um <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/beatforbeat.com.br\/site\/ultra-miami-drone-virginia-key\/\" target=\"_blank\" rel=\"noopener noreferrer\">passeio de drone<\/a><\/span>, <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/beatforbeat.com.br\/site\/ultra-music-festival-iniciativas-sustentaveis\/\" target=\"_blank\" rel=\"noopener noreferrer\">a\u00e7\u00f5es sustent\u00e1veis<\/a><\/span> para diminuir o impacto ambiental causado pelo festival e melhorias nos acessos a ilha, ap\u00f3s diversos coment\u00e1rios negativos nas redes sociais, sobre como chegar ao evento, parece que tudo caminhava bem&#8230; s\u00f3 parecia.<\/p>\n<figure id=\"attachment_17358\" aria-describedby=\"caption-attachment-17358\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/02\/ultra-virginia-key.jpg\"><img decoding=\"async\" class=\"wp-image-17358 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/02\/ultra-virginia-key.jpg\" alt=\"ultra virginia key\" width=\"630\" height=\"365\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/02\/ultra-virginia-key.jpg 760w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/02\/ultra-virginia-key-300x174.jpg 300w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/365;\" \/><\/a><figcaption id=\"caption-attachment-17358\" class=\"wp-caption-text\">Virginia Key<\/figcaption><\/figure>\n<p>A edi\u00e7\u00e3o 2019 do Ultra foi de longe, uma das mais criticadas. Os frequentadores andaram dezenas de quilometros para sair do evento, assim como dentro dele, j\u00e1 que a dist\u00e2ncia entre os palcos era gigantesca, al\u00e9m da estrutura n\u00e3o ser exatamente aquela que todos est\u00e3o acostumados. A logistica n\u00e3o foi nada daquilo que foi prometido e a frustra\u00e7\u00e3o era generalizada, eis ent\u00e3o que come\u00e7ou o &#8220;tira casaco, bota casaco&#8221;.<\/p>\n<p>Em maio deste ano, 2019, o Ultra <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/beatforbeat.com.br\/site\/ultra-music-festival-deixa-miami-em-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">anunciou sua sa\u00edda de Miami<\/a><\/span>, ap\u00f3s 20 anos e colocou em d\u00favida sua edi\u00e7\u00e3o 2020, que ja havia sido anunciada; Logo em seguida, o Homestead Speedway foi um dos grandes cotados para receber o Ultra, assim como a <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/beatforbeat.com.br\/site\/miami-beach-ultra-music-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">Miami Beach<\/a><\/span>. A cidade famosa pelo Spring Break, logo ap\u00f3s o inicio dos rumores, <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/beatforbeat.com.br\/site\/miami-beach-nao-ultra\/\" target=\"_blank\" rel=\"noopener noreferrer\">votou contra<\/a><\/span>. Tudo indicava que a nova casa do festival seria o autodromo de Miami.<\/p>\n<figure id=\"attachment_18343\" aria-describedby=\"caption-attachment-18343\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/05\/Homestead_Aerial.jpg\"><img decoding=\"async\" class=\"wp-image-18343 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/05\/Homestead_Aerial.jpg\" alt=\"Homestead Speedway Ultra\" width=\"630\" height=\"365\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/05\/Homestead_Aerial.jpg 760w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/05\/Homestead_Aerial-300x174.jpg 300w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/365;\" \/><\/a><figcaption id=\"caption-attachment-18343\" class=\"wp-caption-text\">Homestead Speedway<\/figcaption><\/figure>\n<p>Recentemente, em junho, a cidade de Miami voltou atr\u00e1s e decidiu discutir, mais uma vez, sobre o <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/beatforbeat.com.br\/site\/miami-retorno-ultra-bayfront-park\/\" target=\"_blank\" rel=\"noopener noreferrer\">retorno do Ultra ao Bayfront<\/a><\/span>. Alguns disseram sim, outros n\u00e3o, a discuss\u00e3o parecia n\u00e3o ter fim. Vota\u00e7\u00f5es foram feitas e mais uma vez, a proposta negada, at\u00e9 que sem qualquer an\u00fancio, a cidade de Miami decidiu: o Ultra Music Festival est\u00e1 de volta ao Bayfront Park!<\/p>\n<p>Claro que esse retorno n\u00e3o sairia &#8220;de gra\u00e7a&#8221;. Al\u00e9m do pagamento de uma nova taxa de 300 mil dol\u00e1res, que custear\u00e1 bombeiros e policiais, o palco <strong>Biscayne<\/strong> (Oasis) n\u00e3o poder\u00e1 mais existir; dever\u00e1 ser respeitado o limite de 102 dec\u00edbeis e h\u00e1 uma possibilidade de um dos palcos do Resistance tamb\u00e9m ser exclu\u00eddo, para deixar uma \u00e1rea do parque livre, j\u00e1 que a popula\u00e7\u00e3o local, que ainda \u00e9 contra o evento, exige um espa\u00e7o para suas crian\u00e7as brincarem.<\/p>\n<p>Depois de tantas reviravoltas, \u00e9 mais que aceit\u00e1vel que o Ultra acate as novas determina\u00e7\u00f5es, tudo para manter sua casa t\u00e3o tradicional. Em comunicado oficial nas suas redes sociais, o festival comemorou o retorno ao Bayfront Park. Parace que finalmente, toda a novela Ultra chega ao fim e quem ganha, somos n\u00f3s, os Ultralovers. Estamos ansiosos pela edi\u00e7\u00e3o 2020!<\/p>\n<p>https:\/\/www.facebook.com\/Ultra\/videos\/594029837794070\/<\/p>\n","protected":false},"excerpt":{"rendered":"Em uma decis\u00e3o inesperada, a cidade de Miami votou a favor e o Ultra Music Festival retorna ao&hellip;","protected":false},"author":2,"featured_media":18787,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[3],"tags":[1827,143,4286,42,43,3191],"class_list":["post-19252","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mainstage","tag-bayfront-park","tag-miami","tag-miami-beach","tag-ultra","tag-ultra-music-festival","tag-virginia-key","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ultra Music Festival confirma seu retorno ao Bayfront Park<\/title>\n<meta name=\"description\" content=\"Em uma decis\u00e3o inesperada, a cidade de Miami votou a favor e o Ultra Music Festival retorna ao Bayfront Park para sua edi\u00e7\u00e3o 2020. Entenda:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ultra Music Festival confirma seu retorno ao Bayfront Park\" \/>\n<meta property=\"og:description\" content=\"Em uma decis\u00e3o inesperada, a cidade de Miami votou a favor e o Ultra Music Festival retorna ao Bayfront Park para sua edi\u00e7\u00e3o 2020. Entenda:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-26T22:19:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-05T05:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/06\/Ultra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"Ultra Music Festival confirma seu retorno ao Bayfront Park\",\"datePublished\":\"2019-07-26T22:19:36+00:00\",\"dateModified\":\"2019-08-05T05:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/\"},\"wordCount\":627,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Ultra.jpg\",\"keywords\":[\"Bayfront Park\",\"miami\",\"Miami Beach\",\"ultra\",\"Ultra Music Festival\",\"Virginia Key\"],\"articleSection\":[\"Mainstage\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/\",\"name\":\"Ultra Music Festival confirma seu retorno ao Bayfront Park\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Ultra.jpg\",\"datePublished\":\"2019-07-26T22:19:36+00:00\",\"dateModified\":\"2019-08-05T05:00:05+00:00\",\"description\":\"Em uma decis\u00e3o inesperada, a cidade de Miami votou a favor e o Ultra Music Festival retorna ao Bayfront Park para sua edi\u00e7\u00e3o 2020. Entenda:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Ultra.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Ultra.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Ultra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ultra-retorno-bayfront-park\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ultra Music Festival confirma seu retorno ao Bayfront Park\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ultra Music Festival confirma seu retorno ao Bayfront Park","description":"Em uma decis\u00e3o inesperada, a cidade de Miami votou a favor e o Ultra Music Festival retorna ao Bayfront Park para sua edi\u00e7\u00e3o 2020. Entenda:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/","og_locale":"pt_BR","og_type":"article","og_title":"Ultra Music Festival confirma seu retorno ao Bayfront Park","og_description":"Em uma decis\u00e3o inesperada, a cidade de Miami votou a favor e o Ultra Music Festival retorna ao Bayfront Park para sua edi\u00e7\u00e3o 2020. Entenda:","og_url":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2019-07-26T22:19:36+00:00","article_modified_time":"2019-08-05T05:00:05+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/06\/Ultra.jpg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"Ultra Music Festival confirma seu retorno ao Bayfront Park","datePublished":"2019-07-26T22:19:36+00:00","dateModified":"2019-08-05T05:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/"},"wordCount":627,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/06\/Ultra.jpg","keywords":["Bayfront Park","miami","Miami Beach","ultra","Ultra Music Festival","Virginia Key"],"articleSection":["Mainstage"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/","url":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/","name":"Ultra Music Festival confirma seu retorno ao Bayfront Park","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/06\/Ultra.jpg","datePublished":"2019-07-26T22:19:36+00:00","dateModified":"2019-08-05T05:00:05+00:00","description":"Em uma decis\u00e3o inesperada, a cidade de Miami votou a favor e o Ultra Music Festival retorna ao Bayfront Park para sua edi\u00e7\u00e3o 2020. Entenda:","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/06\/Ultra.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2019\/06\/Ultra.jpg","width":1280,"height":720,"caption":"Ultra"},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/ultra-retorno-bayfront-park\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Ultra Music Festival confirma seu retorno ao Bayfront Park"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/19252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=19252"}],"version-history":[{"count":0,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/19252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/18787"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=19252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=19252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=19252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}