{"id":27102,"date":"2021-02-19T01:04:20","date_gmt":"2021-02-19T04:04:20","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=27102"},"modified":"2021-02-19T01:04:45","modified_gmt":"2021-02-19T04:04:45","slug":"estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/","title":{"rendered":"Estados Unidos inicia retomada do entretenimento com pequenos eventos"},"content":{"rendered":"<p>Las Vegas e Nova York, nos Estados Unidos, j\u00e1 decidiram reabrir clubs, arenas e est\u00e1dios com todos os procedimentos contra a covid-19.<br \/>\n<!--more--><\/p>\n<figure id=\"attachment_27103\" aria-describedby=\"caption-attachment-27103\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/liquid.jpg\"><img decoding=\"async\" class=\"wp-image-27103 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/liquid.jpg\" alt=\"Estados Unidos\" width=\"630\" height=\"420\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/liquid.jpg 810w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/liquid-300x200.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/liquid-768x512.jpg 768w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/420;\" \/><\/a><figcaption id=\"caption-attachment-27103\" class=\"wp-caption-text\">Liquid Daylife Club, do Hakkasan Las Vegas<\/figcaption><\/figure>\n<p>Os <strong>Estados Unidos<\/strong> j\u00e1 decidiram iniciar a \u00faltima etapa de retomada econ\u00f4mica ap\u00f3s quase um ano de pandemia do <em>coronav\u00edrus<\/em>. As arenas de <strong>Nova York<\/strong> est\u00e3o reabrindo para eventos ao vivo nesta pr\u00f3xima semana, j\u00e1 <strong>Las Vegas<\/strong>, anunciou que alguns <em>clubs<\/em> e <em>pools<\/em>, ap\u00f3s tanto tempo fechados, reabrir\u00e3o no in\u00edcio de Mar\u00e7o com uma capacidade reduzida.<\/p><div id=\"beatf-3361086176\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>A partir de 23 de Fevereiro, as arenas de <em>NY<\/em> receber\u00e3o aproximadamente 2.000 sentados, socialmente distanciados. Os espectadores dever\u00e3o usar m\u00e1scaras em todos os momentos, exceto enquanto comem ou bebem na \u00e1rea designada. Alimentos, bebidas e outras transa\u00e7\u00f5es ser\u00e3o feitas sem dinheiro, apenas de via remota. Os hot\u00e9is e cassinos de <em>Las Vegas<\/em> tamb\u00e9m dever\u00e3o seguir todas as recomenda\u00e7\u00f5es de distanciamento, funcionando com capacidade reduzida, dividindo-se em mesas de atendimento, com distanciamento social e com cat\u00e1logos e card\u00e1pios em QR CODE e pagamento remoto.<\/p>\n<p>O movimento de retorno do entretenimento presencial faz com que haja certa movimenta\u00e7\u00e3o financeira em um setor que estava h\u00e1 tanto tempo parado. Os clubs de <em>Las Vegas<\/em>, como o <em>Hakkasan<\/em>, <em>OMNIA, ARIA<\/em> e <em>MGM Grand\u2019s Wet Republic<\/em> comemoraram a libera\u00e7\u00e3o dos governos. Nova York tamb\u00e9m poder\u00e1 receber shows nestes estabelecimentos, o <em>Madison Square Garden<\/em>, em <em>Manhattan<\/em> e o <em>Barclays Center<\/em>, no <em>Brooklyn<\/em> foram aprovados para reabrir com 10% da capacidade total das arenas. Com certeza, uma \u00f3tima not\u00edcia para os americanos e um \u00f3timo campo de testes para todo o mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"Las Vegas e Nova York, nos Estados Unidos, j\u00e1 decidiram reabrir clubs, arenas e est\u00e1dios com todos os&hellip;","protected":false},"author":1,"featured_media":27104,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[3],"tags":[9360,6318,9358,5555,6350,9356,1617,217,944,1461,7257,65,9361,163,9359,9357,8268],"class_list":["post-27102","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mainstage","tag-aria","tag-covid-19","tag-day-clubs","tag-economia","tag-entretenimento","tag-esporte","tag-estados-unidos","tag-eua","tag-eventos","tag-hakkasan","tag-hoteis","tag-las-vegas","tag-mgm","tag-nova-york","tag-omnia","tag-pool-parties","tag-retomada","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estados Unidos inicia retomada do entretenimento com pequenos eventos<\/title>\n<meta name=\"description\" content=\"Las Vegas e Nova York, nos Estados Unidos, j\u00e1 decidiram reabrir clubs, arenas e est\u00e1dios com todos os procedimentos contra a covid-19.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estados Unidos inicia retomada do entretenimento com pequenos eventos\" \/>\n<meta property=\"og:description\" content=\"Las Vegas e Nova York, nos Estados Unidos, j\u00e1 decidiram reabrir clubs, arenas e est\u00e1dios com todos os procedimentos contra a covid-19.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-19T04:04:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-19T04:04:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/Pool.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1700\" \/>\n\t<meta property=\"og:image:height\" content=\"1133\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/4dbf95c5732c4cdf103571d9769155ae\"},\"headline\":\"Estados Unidos inicia retomada do entretenimento com pequenos eventos\",\"datePublished\":\"2021-02-19T04:04:20+00:00\",\"dateModified\":\"2021-02-19T04:04:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/\"},\"wordCount\":300,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Pool.jpg\",\"keywords\":[\"ARIA\",\"COVID-19\",\"day clubs\",\"Economia\",\"Entretenimento\",\"esporte\",\"Estados Unidos\",\"EUA\",\"Eventos\",\"Hakkasan\",\"hot\u00e9is\",\"Las Vegas\",\"MGM\",\"Nova York\",\"OMNIA\",\"pool parties\",\"retomada\"],\"articleSection\":[\"Mainstage\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/\",\"name\":\"Estados Unidos inicia retomada do entretenimento com pequenos eventos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Pool.jpg\",\"datePublished\":\"2021-02-19T04:04:20+00:00\",\"dateModified\":\"2021-02-19T04:04:45+00:00\",\"description\":\"Las Vegas e Nova York, nos Estados Unidos, j\u00e1 decidiram reabrir clubs, arenas e est\u00e1dios com todos os procedimentos contra a covid-19.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Pool.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Pool.jpg\",\"width\":1700,\"height\":1133},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estados Unidos inicia retomada do entretenimento com pequenos eventos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/4dbf95c5732c4cdf103571d9769155ae\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estados Unidos inicia retomada do entretenimento com pequenos eventos","description":"Las Vegas e Nova York, nos Estados Unidos, j\u00e1 decidiram reabrir clubs, arenas e est\u00e1dios com todos os procedimentos contra a covid-19.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/","og_locale":"pt_BR","og_type":"article","og_title":"Estados Unidos inicia retomada do entretenimento com pequenos eventos","og_description":"Las Vegas e Nova York, nos Estados Unidos, j\u00e1 decidiram reabrir clubs, arenas e est\u00e1dios com todos os procedimentos contra a covid-19.","og_url":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/","og_site_name":"Beat for Beat","article_published_time":"2021-02-19T04:04:20+00:00","article_modified_time":"2021-02-19T04:04:45+00:00","og_image":[{"width":1700,"height":1133,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/Pool.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/4dbf95c5732c4cdf103571d9769155ae"},"headline":"Estados Unidos inicia retomada do entretenimento com pequenos eventos","datePublished":"2021-02-19T04:04:20+00:00","dateModified":"2021-02-19T04:04:45+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/"},"wordCount":300,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/Pool.jpg","keywords":["ARIA","COVID-19","day clubs","Economia","Entretenimento","esporte","Estados Unidos","EUA","Eventos","Hakkasan","hot\u00e9is","Las Vegas","MGM","Nova York","OMNIA","pool parties","retomada"],"articleSection":["Mainstage"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/","url":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/","name":"Estados Unidos inicia retomada do entretenimento com pequenos eventos","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/Pool.jpg","datePublished":"2021-02-19T04:04:20+00:00","dateModified":"2021-02-19T04:04:45+00:00","description":"Las Vegas e Nova York, nos Estados Unidos, j\u00e1 decidiram reabrir clubs, arenas e est\u00e1dios com todos os procedimentos contra a covid-19.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/Pool.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/02\/Pool.jpg","width":1700,"height":1133},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/estados-unidos-inicia-retomada-do-entretenimento-com-pequenos-eventos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Estados Unidos inicia retomada do entretenimento com pequenos eventos"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/4dbf95c5732c4cdf103571d9769155ae","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/beatforbeat.com.br\/site\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/27102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=27102"}],"version-history":[{"count":0,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/27102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/27104"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=27102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=27102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=27102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}