{"id":27777,"date":"2021-05-05T08:00:31","date_gmt":"2021-05-05T11:00:31","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=27777"},"modified":"2021-05-05T08:00:31","modified_gmt":"2021-05-05T11:00:31","slug":"ortus-diego-planos-desafios-real-supernova-2021","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/","title":{"rendered":"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova"},"content":{"rendered":"<div>\n<p dir=\"ltr\">Confira nosso papo com Ortus e Diego, que nos contam sobre os pr\u00f3ximos passos da Real Supernova para os pr\u00f3ximos meses deste ano.<\/p>\n<p dir=\"ltr\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova.png\"><img decoding=\"async\" class=\"aligncenter wp-image-27778 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova.png\" alt=\"Ortus Diego\" width=\"630\" height=\"354\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova.png 1920w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova-300x169.png 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova-1024x576.png 1024w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova-768x432.png 768w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova-1536x864.png 1536w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova-600x337.png 600w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/354;\" \/><\/a><\/p>\n<p dir=\"ltr\">Comandar uma gravadora pode ter se tornado algo mais simples no momento atual com as facilidades tecnol\u00f3gicas e a desburocratiza\u00e7\u00e3o dessa pr\u00e1tica, mas ainda assim exige compromisso daqueles que est\u00e3o \u00e0 frente da iniciativa. Criar uma identidade sonora (e visual), buscar por artistas, ouvir demos, mixar, masterizar, cuidar da assinatura de contrato, divulgar os releases e entre outras atividades exige tempo, paci\u00eancia e cuidado.<\/p><div id=\"beatf-82150557\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p dir=\"ltr\">Ao longo de 2020, a <strong>Real Supernova<\/strong>, gravadora capitaneada por <strong>Ortus (BR)<\/strong> e <strong>Diego Ruiz<\/strong>, fez um \u00f3timo trabalho dentro da cena nacional lan\u00e7ando sete EPs valorizando o trabalho de produtores brazucas, mas tamb\u00e9m abrindo espa\u00e7o para novos nomes l\u00e1 de fora, como <em>Marc Erberich<\/em>. No in\u00edcio de 2021, uma breve pausa para realinhar objetivos e tra\u00e7ar novas rotas espaciais em busca de produ\u00e7\u00f5es singulares para compor o cat\u00e1logo, plano que eles compartilham um pouco mais neste bate-papo:<\/p>\n<p><iframe title=\"Spotify Embed: Analog Answer EP\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" data-src=\"https:\/\/open.spotify.com\/embed\/album\/1x70oQrHHsm5ocHWTlEfsE?si=e302tqPhQMiVF884mVv5Qw&#038;utm_source=oembed\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p dir=\"ltr\"><strong>Primeiramente: nos contem um pouquinho o que motivou voc\u00eas idealizarem a Real Supernova? Quanto tempo ela ficou incubada at\u00e9 ganhar vida e ter o primeiro lan\u00e7amento em fevereiro do ano passado?<\/strong><\/p>\n<p dir=\"ltr\"><span style=\"color: #ff6600;\"><strong>Ortus\/Diego<\/strong><\/span> \u2013 Tivemos in\u00fameras reuni\u00f5es para finalmente chegar no que quer\u00edamos, foram meses de ideias e refer\u00eancias para alinhar um projeto que fosse exatamente o que est\u00e1vamos planejando. A ideia inicial nunca foi somente uma gravadora, na verdade A Real Supernova \u00e9 uma marca, que em um futuro bem pr\u00f3ximo, vamos ter eventos, cole\u00e7\u00e3o de roupas e acess\u00f3rios e at\u00e9 um casting de artistas. Estamos cada vez mais pr\u00f3ximos desses objetivos.<\/p>\n<p dir=\"ltr\"><strong>Como foi para chegar na defini\u00e7\u00e3o do nome\/conceito da gravadora? Quem \u00e9 o respons\u00e1vel por tr\u00e1s dos artworks de cada EP?\u00a0<\/strong><\/p>\n<p dir=\"ltr\"><span style=\"color: #ff6600;\"><strong>Ortus\/Diego<\/strong><\/span> \u2013 A ideia inicial era algo espacial, afinal essa \u00e9 a identidade principal da gravadora. Uma supernova \u00e9 uma explos\u00e3o estelar poderosa e luminosa. Ent\u00e3o pensamos em construir todo o conceito em torno desse acontecimento, e todo o material de m\u00eddia tem essa identidade. O respons\u00e1vel pela parte art\u00edstica das covers \u00e9 o Diego, toda a parte de v\u00eddeo \u00e9 terceirizada e aprova\u00e7\u00e3o de todo o material \u00e9 feito pelos dois.<\/p>\n<p dir=\"ltr\"><strong>A Real Supernova tem uma conex\u00e3o com o fen\u00f4meno astron\u00f4mico e, tamb\u00e9m, tenta trazer essa atmosfera \u2018espacial\u2019 pros lan\u00e7amentos, certo? Como \u201ccaptar\u201d essa ess\u00eancia e aplicar na m\u00fasica? Voc\u00eas t\u00eam alguma dica?<\/strong><\/p>\n<p dir=\"ltr\"><span style=\"color: #ff6600;\"><strong>Ortus\/Diego<\/strong><\/span> \u2013\u00a0 Sim, a nossa gravadora n\u00e3o tem um estilo espec\u00edfico, variamos entre o Melodic House &amp; Techno, Downtempo e Techno, temos m\u00fasicas lan\u00e7adas em diferentes BPMs, a ideia principal \u00e9 parecer um som &#8216;espacial&#8217;, para que quando as pessoas ou\u00e7am, elas tenham uma sensa\u00e7\u00e3o que remete uma experi\u00eancia espacial.<\/p>\n<p><iframe title=\"Spotify Embed: Sidereum EP\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" data-src=\"https:\/\/open.spotify.com\/embed\/album\/0OVJ1TR6gt3lh4vn2DxLC0?si=L1uee5s_RkWmp1NEOeJwnQ&#038;utm_source=oembed\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p dir=\"ltr\"><strong>Bem, teve uma pausa nos lan\u00e7amentos nesse in\u00edcio de 2021\u2026 o que voc\u00eas est\u00e3o planejando para os pr\u00f3ximos meses? J\u00e1 possuem algum novo artista confirmado?\u00a0<\/strong><\/p>\n<p dir=\"ltr\"><span style=\"color: #ff6600;\"><strong>Ortus\/Diego<\/strong><\/span> \u2013 Temos recebido algumas demos, e desde o ano passado estamos selecionando as tracks para o nosso primeiro V.A. Em breve vamos ter o primeiro lan\u00e7amento de 2021.<\/p>\n<p dir=\"ltr\"><strong>Como headlabels, quais s\u00e3o as principais dificuldades que voc\u00eas enfrentam no comando do selo?\u00a0<\/strong><\/p>\n<p dir=\"ltr\"><span style=\"color: #ff6600;\"><strong>Ortus\/Diego<\/strong> <\/span>\u2013 Acho que o artista, antes de mandar qualquer m\u00fasica para qualquer selo, deve estud\u00e1-lo, ver os \u00faltimos lan\u00e7amentos e tentar enviar um som que seja enquadrado na label. Recebemos muitas demos de muita qualidade, mas tamb\u00e9m recebemos algumas coisas que n\u00e3o tem nada a ver com o conceito da label. Ent\u00e3o se fosse enviado algo direcionado pra label, a chance de dar certo \u00e9 muito maior. Temos muita cautela em escolher o que vamos lan\u00e7ar, existe um custo alto para que o lan\u00e7amento seja realizado, ent\u00e3o tem que ser algo que seja 100% do nosso agrado e principalmente o artista se sinta muito a vontade de entrar pra nossa fam\u00edlia.<\/p>\n<p dir=\"ltr\"><strong>Alguma dica ou conselho para quem tamb\u00e9m deseja criar sua pr\u00f3pria gravadora?\u00a0<\/strong><\/p>\n<p dir=\"ltr\"><span style=\"color: #ff6600;\"><strong>Ortus\/Diego<\/strong><\/span> \u2013\u00a0 Projete algo com tempo, amadure\u00e7a as ideias, e tente ter algo diferencial no mercado. Hoje em dia qualquer um pode ter uma gravadora, mas para termos bons resultados nas m\u00eddias e em vendas, requer muita dedica\u00e7\u00e3o e tempo. Confessamos que com todos os nossos compromissos nas nossas carreiras pessoais, \u00e9 dif\u00edcil conciliar o tempo para termos bons resultados na gravadora, mas cada vez mais estamos nos alinhando para organizarmos tudo. No \u00faltimo m\u00eas, recrutamos um grande amigo e artista da Label para nos ajudar nos trabalhos da label. Cruxz, que j\u00e1 lan\u00e7ou com a gente, vai nos ajudar em algumas \u00e1reas para crescermos ainda mais.<\/p>\n<\/div>\n<p><span style=\"font-family: verdana, sans-serif;\">Veja todos os lan\u00e7amentos da Real Supernova no\u00a0<a tabindex=\"-1\" href=\"https:\/\/www.beatport.com\/label\/real-supernova-records\/83627\/tracks\" target=\"_blank\" rel=\"external noopener\">Beatport<\/a>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"Confira nosso papo com Ortus e Diego, que nos contam sobre os pr\u00f3ximos passos da Real Supernova para&hellip;","protected":false},"author":2,"featured_media":27778,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[14],"tags":[9783,9784,9782,6666],"class_list":["post-27777","post","type-post","status-publish","format-standard","has-post-thumbnail","category-via-underground","tag-diego-ruiz","tag-marc-erberich","tag-ortus-br","tag-real-supernova","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova<\/title>\n<meta name=\"description\" content=\"Confira nosso papo com Ortus e Diego, que nos contam sobre os pr\u00f3ximos passos da Real Supernova para os pr\u00f3ximos meses deste ano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova\" \/>\n<meta property=\"og:description\" content=\"Confira nosso papo com Ortus e Diego, que nos contam sobre os pr\u00f3ximos passos da Real Supernova para os pr\u00f3ximos meses deste ano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-05T11:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova\",\"datePublished\":\"2021-05-05T11:00:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/\"},\"wordCount\":856,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Diego-e-Ortus-Real-Supernova.png\",\"keywords\":[\"Diego Ruiz\",\"Marc Erberich\",\"Ortus (BR)\",\"Real Supernova\"],\"articleSection\":[\"Via UnderGROUND\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/\",\"name\":\"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Diego-e-Ortus-Real-Supernova.png\",\"datePublished\":\"2021-05-05T11:00:31+00:00\",\"description\":\"Confira nosso papo com Ortus e Diego, que nos contam sobre os pr\u00f3ximos passos da Real Supernova para os pr\u00f3ximos meses deste ano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Diego-e-Ortus-Real-Supernova.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Diego-e-Ortus-Real-Supernova.png\",\"width\":1920,\"height\":1080,\"caption\":\"Ortus Diego\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/ortus-diego-planos-desafios-real-supernova-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova","description":"Confira nosso papo com Ortus e Diego, que nos contam sobre os pr\u00f3ximos passos da Real Supernova para os pr\u00f3ximos meses deste ano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/","og_locale":"pt_BR","og_type":"article","og_title":"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova","og_description":"Confira nosso papo com Ortus e Diego, que nos contam sobre os pr\u00f3ximos passos da Real Supernova para os pr\u00f3ximos meses deste ano.","og_url":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2021-05-05T11:00:31+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova-1024x576.png","type":"image\/png"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova","datePublished":"2021-05-05T11:00:31+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/"},"wordCount":856,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova.png","keywords":["Diego Ruiz","Marc Erberich","Ortus (BR)","Real Supernova"],"articleSection":["Via UnderGROUND"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/","url":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/","name":"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova.png","datePublished":"2021-05-05T11:00:31+00:00","description":"Confira nosso papo com Ortus e Diego, que nos contam sobre os pr\u00f3ximos passos da Real Supernova para os pr\u00f3ximos meses deste ano.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2021\/05\/Diego-e-Ortus-Real-Supernova.png","width":1920,"height":1080,"caption":"Ortus Diego"},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/ortus-diego-planos-desafios-real-supernova-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Ortus e Diego Ruiz comentam os planos e desafios da Real Supernova"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/27777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=27777"}],"version-history":[{"count":0,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/27777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/27778"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=27777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=27777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=27777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}