{"id":30674,"date":"2022-01-05T10:12:30","date_gmt":"2022-01-05T13:12:30","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=30674"},"modified":"2022-01-05T10:12:30","modified_gmt":"2022-01-05T13:12:30","slug":"duo-gheist-video-we-are-not-alone","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/","title":{"rendered":"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental"},"content":{"rendered":"<p>A track \u2018We Are Not Alone\u2019, do duo GHEIST, ganhou um v\u00eddeo oficial que promove a preven\u00e7\u00e3o da sa\u00fade mental, principalmente na pandemia.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-30675 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629.jpg\" alt=\"GHEIST\" width=\"630\" height=\"452\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629.jpg 1600w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629-300x215.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629-1024x735.jpg 1024w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629-768x551.jpg 768w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629-1536x1102.jpg 1536w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/452;\" \/><\/a><\/p>\n<p>Alguns temas, como o cuidado com a sa\u00fade mental, deveriam ser recorrentes na ind\u00fastria musical e n\u00e3o limitados a a\u00e7\u00f5es como o setembro amarelo e foi pensando nisso, em conscientizar as pessoas quando necess\u00e1rio, que a dupla alem\u00e3, <strong>GHEIST<\/strong>, lan\u00e7ou seu v\u00eddeo clipe, principalmente ap\u00f3s tantos meses de uma pandemia que parece nunca ter fim e que tanto nos atingiu.<\/p><div id=\"beatf-51019335\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>A m\u00fasica, &#8216;<em>We Are Not Alone<\/em>&#8216;, em tradu\u00e7\u00e3o livre, &#8216;N\u00f3s N\u00e3o Estamos Sozinhos&#8217;, faz parte do \u00faltimo <a href=\"https:\/\/open.spotify.com\/album\/7egVvoX1tiHQDFPXJKYNfA\" target=\"_blank\" rel=\"noopener\">\u00e1lbum<\/a> do duo, <strong>Zukunft<\/strong>, lan\u00e7ado em novembro de 2021 pela <strong>Radau Music<\/strong>. O v\u00eddeo, que aborda o assunto sobre a sa\u00fade mental, \u00e9 muito importante para a dupla que, recentemente, perdeu seu grande amigo e tour manager, que interrompeu a vida e cometeu suic\u00eddio. O clipe, \u00e9 tamb\u00e9m um grande alerta para todos n\u00f3s.<\/p>\n<p>&#8220;<em>Saindo desses \u00faltimos 18 meses exaustivos e estranhos, parece haver um t\u00f3pico que sempre esteve ao nosso redor, mas agora parece maior do que nunca. Estivemos isolados, estivemos sozinhos e em grande risco de sofrer de depress\u00e3o. \u00c9 uma quest\u00e3o do cora\u00e7\u00e3o falarmos sobre esse triste fen\u00f4meno e falar alto sobre ele. Recentemente, perdemos um amigo pr\u00f3ximo que cometeu suic\u00eddio e ningu\u00e9m previu isso.<\/em> &#8221; diz a a dupla GHEIST.<\/p>\n<p>A dupla ressalta que \u00e9 importante, para a categoria art\u00edstica como um todo, apontar essa quest\u00e3o toda, criar espa\u00e7os seguros para discuss\u00e3o e ajudar a desestigmatizar a doen\u00e7a mental como algo proibido de ser falado. \u00c9 preciso que todos nos sensibilizemos e ajudemos, principalmente, pessoas com tend\u00eancias suicidas. Ningu\u00e9m pode ser deixado de lado ou para tr\u00e1s. Vamos cuidar uns dos outros. N\u00f3s n\u00e3o estamos sozinhos!<\/p>\n<p>Assista agora ao clipe e que essa mensagem, possa te atingir, positivamente e te inspire em ajudar as pessoas pr\u00f3ximas a voc\u00ea. Comece fazendo a diferen\u00e7a:<\/p>\n<p><iframe title=\"GHEIST - We Are Not Alone\" data-src=\"https:\/\/player.vimeo.com\/video\/568527183?dnt=1&amp;app_id=122963\" width=\"1200\" height=\"675\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"A track \u2018We Are Not Alone\u2019, do duo GHEIST, ganhou um v\u00eddeo oficial que promove a preven\u00e7\u00e3o da&hellip;","protected":false},"author":2,"featured_media":30675,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[3],"tags":[53,11068,11070,4126,304,11071,11069],"class_list":["post-30674","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mainstage","tag-dj","tag-gheist","tag-radau-music","tag-saude-mental","tag-video","tag-we-are-not-alone","tag-zukunft","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental<\/title>\n<meta name=\"description\" content=\"A track \u2018We Are Not Alone\u2019, do duo GHEIST, ganhou um v\u00eddeo oficial que promove a preven\u00e7\u00e3o da sa\u00fade mental, principalmente na pandemia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental\" \/>\n<meta property=\"og:description\" content=\"A track \u2018We Are Not Alone\u2019, do duo GHEIST, ganhou um v\u00eddeo oficial que promove a preven\u00e7\u00e3o da sa\u00fade mental, principalmente na pandemia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-05T13:12:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental\",\"datePublished\":\"2022-01-05T13:12:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GHEIST_1-e1641388192629.jpg\",\"keywords\":[\"DJ\",\"GHEIST\",\"Radau Music\",\"sa\u00fade mental\",\"video\",\"We Are Not Alone\",\"Zukunft\"],\"articleSection\":[\"Mainstage\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/\",\"name\":\"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GHEIST_1-e1641388192629.jpg\",\"datePublished\":\"2022-01-05T13:12:30+00:00\",\"description\":\"A track \u2018We Are Not Alone\u2019, do duo GHEIST, ganhou um v\u00eddeo oficial que promove a preven\u00e7\u00e3o da sa\u00fade mental, principalmente na pandemia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GHEIST_1-e1641388192629.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GHEIST_1-e1641388192629.jpg\",\"width\":1600,\"height\":1148,\"caption\":\"GHEIST\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/duo-gheist-video-we-are-not-alone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental","description":"A track \u2018We Are Not Alone\u2019, do duo GHEIST, ganhou um v\u00eddeo oficial que promove a preven\u00e7\u00e3o da sa\u00fade mental, principalmente na pandemia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/","og_locale":"pt_BR","og_type":"article","og_title":"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental","og_description":"A track \u2018We Are Not Alone\u2019, do duo GHEIST, ganhou um v\u00eddeo oficial que promove a preven\u00e7\u00e3o da sa\u00fade mental, principalmente na pandemia.","og_url":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2022-01-05T13:12:30+00:00","og_image":[{"width":1600,"height":1148,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629.jpg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental","datePublished":"2022-01-05T13:12:30+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/"},"wordCount":368,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629.jpg","keywords":["DJ","GHEIST","Radau Music","sa\u00fade mental","video","We Are Not Alone","Zukunft"],"articleSection":["Mainstage"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/","url":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/","name":"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629.jpg","datePublished":"2022-01-05T13:12:30+00:00","description":"A track \u2018We Are Not Alone\u2019, do duo GHEIST, ganhou um v\u00eddeo oficial que promove a preven\u00e7\u00e3o da sa\u00fade mental, principalmente na pandemia.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/01\/GHEIST_1-e1641388192629.jpg","width":1600,"height":1148,"caption":"GHEIST"},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/duo-gheist-video-we-are-not-alone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"GHEIST lan\u00e7a v\u00eddeo que promove o cuidado com a sa\u00fade mental"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/30674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=30674"}],"version-history":[{"count":0,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/30674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/30675"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=30674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=30674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=30674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}