{"id":34319,"date":"2022-10-07T00:12:05","date_gmt":"2022-10-07T03:12:05","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=34319"},"modified":"2022-10-07T00:12:05","modified_gmt":"2022-10-07T03:12:05","slug":"d-edge-apresenta-gordo-no-18o-aniversario-da-moving","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/","title":{"rendered":"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving"},"content":{"rendered":"<p>DJ e produtor guatemalteco vem em tour pelo brasil com seu novo projeto de tech-house.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-34323 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2.jpg\" alt=\"Gordo\" width=\"630\" height=\"787\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2.jpg 1080w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2-240x300.jpg 240w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2-820x1024.jpg 820w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2-768x959.jpg 768w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/787;\" \/><\/a><\/p>\n<p>Antes conhecido como &#8220;carnage&#8221;, Diamant\u00e9 Anthony Blackmon decidiu se aventurar pelo house com seu novo projeto &#8220;Gordo&#8221;.<\/p><div id=\"beatf-2016751258\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Se como &#8220;Carnage&#8221;, o Guatamalteco j\u00e1 havia alcan\u00e7ado o topo das principais paradas internacionais, e marcado presen\u00e7a nos principais festivais do mundo com seu dubstep e trap caracter\u00edstico, neste novo projeto ele aposta em um som mais dan\u00e7ante recheado de tech-house.<\/p>\n<p>Para acompanhar Gordo nesta noite, foram escolhidos dois grandes nomes do tech house nacional, Gabe e Bruno Furlan.<\/p>\n<p>Gabe, o rei das chineladas, dispensa introdu\u00e7\u00f5es e volta a d-edge, ap\u00f3s uma grande sequencia de apresenta\u00e7\u00f5es, que incluem um all night long de sucesso e uma grande apresenta\u00e7\u00e3o no Rock in Rio.<\/p>\n<p>J\u00e1, Bruno Furlan, \u00e9 um fen\u00f4meno que com apenas 22 anos j\u00e1 tinha se estabelecido na cena nacional com um estilo \u00fanico de som que chamou a aten\u00e7\u00e3o de gigantes internacionais como Claude VonStroke, Chris Lake, Solardo, Green Velvet, Amine Edge &amp; Dance, Fisher e Jamie Jones.<\/p>\n<p>Para completar a noite na pista 2 os DJ&#8217;s escalados foram: Teclas, EINMUSIK e Riko e Gugga.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-e-gabe-1.jpg\"><img decoding=\"async\" class=\"wp-image-34324 aligncenter lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-e-gabe-1.jpg\" alt=\"gordo\" width=\"630\" height=\"427\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-e-gabe-1.jpg 656w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-e-gabe-1-300x204.jpg 300w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/427;\" \/><\/a><\/p>\n<p><strong>SERVI\u00c7O:<\/strong><\/p>\n<p><strong>MOVING 18TH ANNIV w\/ Gordo\u00a0<\/strong><\/p>\n<p>Horario: 23:59 as 8h.<br \/>\nEndere\u00e7o: Av. M\u00e1rio de Andrade, 141 &#8211; Barra Funda, S\u00e3o Paulo &#8211; SP, 01156-001<br \/>\nData: 13\/10 ( quinta feira)<br \/>\nLine-up: Bruno Furlan, Gordo, Gabe, Teclas, EINMUSIK, Riko &amp; Gugga<br \/>\nIngressos: Dispon\u00edveis na Sympla, clicando <a href=\"https:\/\/www.sympla.com.br\/evento\/moving-18th-anniv-w-gordo-einmusik-gabe-bruno-furlan-teclas-riko-gugga\/1734580\" target=\"_blank\" rel=\"noopener\">aqui.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"DJ e produtor guatemalteco vem em tour pelo brasil com seu novo projeto de tech-house. Antes conhecido como&hellip;","protected":false},"author":2,"featured_media":34323,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[6],"tags":[417,171,8357,117,11433,12027,10381],"class_list":["post-34319","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda","tag-bruno-furlan","tag-d-edge","tag-einmusik","tag-gabe","tag-gordo","tag-riko-gugga","tag-teclas","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D-edge apresenta Gordo no 18\u00ba Aniversario da Moving<\/title>\n<meta name=\"description\" content=\"DJ e produtor guatemalteco vem em tour pelo brasil com seu novo projeto de tech-house e comanda a d-edge junto com Gabe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving\" \/>\n<meta property=\"og:description\" content=\"DJ e produtor guatemalteco vem em tour pelo brasil com seu novo projeto de tech-house e comanda a d-edge junto com Gabe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-07T03:12:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving\",\"datePublished\":\"2022-10-07T03:12:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/\"},\"wordCount\":249,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/gordo-2.jpg\",\"keywords\":[\"Bruno Furlan\",\"D-Edge\",\"Einmusik\",\"gabe\",\"Gordo\",\"Riko &amp; Gugga\",\"Teclas\"],\"articleSection\":[\"Agenda\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/\",\"name\":\"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/gordo-2.jpg\",\"datePublished\":\"2022-10-07T03:12:05+00:00\",\"description\":\"DJ e produtor guatemalteco vem em tour pelo brasil com seu novo projeto de tech-house e comanda a d-edge junto com Gabe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/gordo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/gordo-2.jpg\",\"width\":1080,\"height\":1349},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving","description":"DJ e produtor guatemalteco vem em tour pelo brasil com seu novo projeto de tech-house e comanda a d-edge junto com Gabe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/","og_locale":"pt_BR","og_type":"article","og_title":"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving","og_description":"DJ e produtor guatemalteco vem em tour pelo brasil com seu novo projeto de tech-house e comanda a d-edge junto com Gabe.","og_url":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2022-10-07T03:12:05+00:00","og_image":[{"width":1080,"height":1349,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2.jpg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving","datePublished":"2022-10-07T03:12:05+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/"},"wordCount":249,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2.jpg","keywords":["Bruno Furlan","D-Edge","Einmusik","gabe","Gordo","Riko &amp; Gugga","Teclas"],"articleSection":["Agenda"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/","url":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/","name":"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2.jpg","datePublished":"2022-10-07T03:12:05+00:00","description":"DJ e produtor guatemalteco vem em tour pelo brasil com seu novo projeto de tech-house e comanda a d-edge junto com Gabe.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2022\/10\/gordo-2.jpg","width":1080,"height":1349},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/d-edge-apresenta-gordo-no-18o-aniversario-da-moving\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"D-edge apresenta Gordo no 18\u00ba Aniversario da Moving"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/34319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=34319"}],"version-history":[{"count":4,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/34319\/revisions"}],"predecessor-version":[{"id":34397,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/34319\/revisions\/34397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/34323"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=34319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=34319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=34319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}