{"id":40221,"date":"2023-10-26T18:35:19","date_gmt":"2023-10-26T21:35:19","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=40221"},"modified":"2023-10-26T18:35:19","modified_gmt":"2023-10-26T21:35:19","slug":"zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/","title":{"rendered":"ZUSO traz a calma e o escapismo em novo single &#8216;Hold Me&#8217;"},"content":{"rendered":"<p>Atmosferas calmantes e escapismo s\u00e3o temas recorrentes na maioria das m\u00fasicas do ZUSO, e &#8216;Hold Me&#8217; possui ambos em abund\u00e2ncia. Escute.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-40222 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989.jpg\" alt=\"ZUSO\" width=\"630\" height=\"491\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989.jpg 1288w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989-300x234.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989-1024x798.jpg 1024w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989-768x599.jpg 768w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/491;\" \/><\/a><\/p>\n<p><strong>ZUSO<\/strong> \u00e9 um projeto do produtor australiano Gabriel Cuenca, que est\u00e1 criando um som envolvente de house atmosf\u00e9rico que pode ser comparado a uma mistura entre Rufus Du Sol, Lane 8 e Flume. Nos \u00faltimos meses, Gabriel nos presenteou com tr\u00eas singles excepcionais do ZUSO: &#8216;Higher&#8217;, &#8216;Aurora&#8217; e &#8216;Miss You&#8217;, prometendo ainda mais novidades em breve. Esta semana, ele est\u00e1 cumprindo essa promessa ao nos presentear com seu mais novo single <em>&#8216;Hold Me&#8217;<\/em>, lan\u00e7ado atrav\u00e9s da <strong>LOVE CLVB<\/strong>. Ou\u00e7a <a href=\"https:\/\/open.spotify.com\/track\/3y54PvUPngWdp0zuM7SpOj\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p><div id=\"beatf-3995249336\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p><em>&#8220;&#8216;Hold Me&#8217; \u00e9 uma brisa suave de ar fresco. \u00c9 muito legal poder combinar esse tipo de som dnb com o meu pr\u00f3prio estilo e texturas. Escrevi a batida rapidamente e depois encontrei a amostra vocal em um pacote de samples que lembro de ter usado h\u00e1 muito tempo em uma das primeiras demos que fiz. Ela tinha uma vibra\u00e7\u00e3o t\u00e3o agrad\u00e1vel e suave que eu realmente adorei. Queria que a m\u00fasica transmitisse essa energia calmante e reconfortante, e a amostra vocal de &#8216;Hold Me&#8217; se encaixa perfeitamente nesse tom. Definitivamente, tamb\u00e9m possui uma sensa\u00e7\u00e3o de escapismo, que \u00e9 um tema comum em muitas das minhas m\u00fasicas. Depois, adicionei alguns acordes e pads emocionalmente carregados, junto com um riff de guitarra agrad\u00e1vel, apenas para intensificar esse sentimento. Espero que seja algo com o qual todos voc\u00eas possam se identificar e desfrutar&#8221;, <\/em>diz o artista.<\/p>\n<p>Escute agora &#8216;Hold Me&#8217;:<\/p>\n<p><iframe title=\"Spotify Embed: Hold Me\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" data-src=\"https:\/\/open.spotify.com\/embed\/track\/3y54PvUPngWdp0zuM7SpOj?utm_source=oembed\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"Atmosferas calmantes e escapismo s\u00e3o temas recorrentes na maioria das m\u00fasicas do ZUSO, e &#8216;Hold Me&#8217; possui ambos&hellip;","protected":false},"author":2,"featured_media":40222,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[7938],"tags":[10309,16003,13869],"class_list":["post-40221","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lancamentos","tag-hold-me","tag-love-clvb","tag-zuso","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZUSO traz a calma e o escapismo em novo single &#039;Hold Me&#039;<\/title>\n<meta name=\"description\" content=\"Atmosferas calmantes e escapismo s\u00e3o temas recorrentes na maioria das m\u00fasicas do ZUSO, e &#039;Hold Me&#039; possui ambos em abund\u00e2ncia. Escute.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZUSO traz a calma e o escapismo em novo single &#039;Hold Me&#039;\" \/>\n<meta property=\"og:description\" content=\"Atmosferas calmantes e escapismo s\u00e3o temas recorrentes na maioria das m\u00fasicas do ZUSO, e &#039;Hold Me&#039; possui ambos em abund\u00e2ncia. Escute.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-26T21:35:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1288\" \/>\n\t<meta property=\"og:image:height\" content=\"1004\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"ZUSO traz a calma e o escapismo em novo single &#8216;Hold Me&#8217;\",\"datePublished\":\"2023-10-26T21:35:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/\"},\"wordCount\":283,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ZUSO-photo-1-e1698356092989.jpg\",\"keywords\":[\"Hold Me\",\"LOVE CLVB\",\"ZUSO\"],\"articleSection\":[\"Lan\u00e7amentos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/\",\"name\":\"ZUSO traz a calma e o escapismo em novo single 'Hold Me'\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ZUSO-photo-1-e1698356092989.jpg\",\"datePublished\":\"2023-10-26T21:35:19+00:00\",\"description\":\"Atmosferas calmantes e escapismo s\u00e3o temas recorrentes na maioria das m\u00fasicas do ZUSO, e 'Hold Me' possui ambos em abund\u00e2ncia. Escute.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ZUSO-photo-1-e1698356092989.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ZUSO-photo-1-e1698356092989.jpg\",\"width\":1288,\"height\":1004,\"caption\":\"ZUSO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZUSO traz a calma e o escapismo em novo single &#8216;Hold Me&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZUSO traz a calma e o escapismo em novo single 'Hold Me'","description":"Atmosferas calmantes e escapismo s\u00e3o temas recorrentes na maioria das m\u00fasicas do ZUSO, e 'Hold Me' possui ambos em abund\u00e2ncia. Escute.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/","og_locale":"pt_BR","og_type":"article","og_title":"ZUSO traz a calma e o escapismo em novo single 'Hold Me'","og_description":"Atmosferas calmantes e escapismo s\u00e3o temas recorrentes na maioria das m\u00fasicas do ZUSO, e 'Hold Me' possui ambos em abund\u00e2ncia. Escute.","og_url":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2023-10-26T21:35:19+00:00","og_image":[{"width":1288,"height":1004,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989.jpg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"ZUSO traz a calma e o escapismo em novo single &#8216;Hold Me&#8217;","datePublished":"2023-10-26T21:35:19+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/"},"wordCount":283,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989.jpg","keywords":["Hold Me","LOVE CLVB","ZUSO"],"articleSection":["Lan\u00e7amentos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/","url":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/","name":"ZUSO traz a calma e o escapismo em novo single 'Hold Me'","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989.jpg","datePublished":"2023-10-26T21:35:19+00:00","description":"Atmosferas calmantes e escapismo s\u00e3o temas recorrentes na maioria das m\u00fasicas do ZUSO, e 'Hold Me' possui ambos em abund\u00e2ncia. Escute.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2023\/10\/ZUSO-photo-1-e1698356092989.jpg","width":1288,"height":1004,"caption":"ZUSO"},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/zuso-traz-a-calma-e-o-escapismo-em-novo-single-hold-me\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"ZUSO traz a calma e o escapismo em novo single &#8216;Hold Me&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/40221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=40221"}],"version-history":[{"count":1,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/40221\/revisions"}],"predecessor-version":[{"id":40223,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/40221\/revisions\/40223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/40222"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=40221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=40221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=40221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}