{"id":41917,"date":"2024-02-21T14:07:07","date_gmt":"2024-02-21T17:07:07","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=41917"},"modified":"2024-02-21T14:07:07","modified_gmt":"2024-02-21T17:07:07","slug":"pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/","title":{"rendered":"Pacha e Destino Ibiza anunciam festas de abertura de 2024"},"content":{"rendered":"<p>Com Marco Carola e PAWSA, Pacha e Destino Ibiza divulgam as opening parties do ver\u00e3o de 2024 em Ibiza, Espanha.<\/p>\n<figure id=\"attachment_41918\" aria-describedby=\"caption-attachment-41918\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Marco-Carola-Pacha.jpg\"><img decoding=\"async\" class=\"wp-image-41918 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Marco-Carola-Pacha-300x200.jpg\" alt=\"Pacha\" width=\"630\" height=\"420\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Marco-Carola-Pacha-300x200.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Marco-Carola-Pacha.jpg 740w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/420;\" \/><\/a><figcaption id=\"caption-attachment-41918\" class=\"wp-caption-text\">Marco Carola no Pacha Ibiza (Divulga\u00e7\u00e3o)<\/figcaption><\/figure>\n<p>N\u00e3o h\u00e1 maior aviso de que o ver\u00e3o europeu est\u00e1 \u00e0 caminho do que os an\u00fancios dos clubs de Ibiza. \u00c0 medida em que a temporada de 2024 se aproxima, clubs como Ushuaia Ibiza e Hi Ibiza j\u00e1 divulgaram suas resid\u00eancias, agora chegou a vez dos ic\u00f4nicos clubs Pacha e Destino Ibiza, que tamb\u00e9m est\u00e3o entre os primeiros a anunciar suas festas de abertura, oferecendo um gostinho de um ver\u00e3o emocionante na ilha.<\/p><div id=\"beatf-274702905\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Iniciando o fim de semana de 26 a 28 de abril, Pacha e Destino Ibiza abrem suas portas com Marco Carola, acompanhado por um dos embaixadores do house mundial ANOTR, al\u00e9m de Desiree, Ale de Tuglie e Calvin Clarke. J\u00e1 podemos esperar um dos grooves mais potentes deste in\u00edcio de temporada na ic\u00f4nica cidade espanhola.<\/p>\n<p>O famoso club de Ibiza traz sempre grandes resid\u00eancias em seu ver\u00e3o, em 2023 estiveram Bedouin, Robin Schulz, Music On por Marco Carola, The Masquerade por Claptone e Solomun. Ainda n\u00e3o foram divulgadas as resid\u00eancias deste ano, mas podemos aguardar a maioria destes nomes no calend\u00e1rio.<\/p>\n<p>Os ingressos para os eventos as opening parties do Pacha e Destino Ibiza est\u00e3o dispon\u00edveis online e neste <a href=\"https:\/\/pacha.com\/events\" target=\"_blank\" rel=\"noopener\">link<\/a>. Visite o site oficial para mais informa\u00e7\u00f5es.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha-2.webp\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-41920 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha-2-270x300.webp\" alt=\"\" width=\"270\" height=\"300\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha-2-270x300.webp 270w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha-2.webp 468w\" data-sizes=\"(max-width: 270px) 100vw, 270px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 270px; --smush-placeholder-aspect-ratio: 270\/300;\" \/><\/a> <a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Opening-Pacha.webp\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-41921 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Opening-Pacha-270x300.webp\" alt=\"\" width=\"270\" height=\"300\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Opening-Pacha-270x300.webp 270w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Opening-Pacha.webp 468w\" data-sizes=\"(max-width: 270px) 100vw, 270px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 270px; --smush-placeholder-aspect-ratio: 270\/300;\" \/><\/a><br \/>\nPosters de an\u00fancio das opening parties da Pacha Ibiza (Divulga\u00e7\u00e3o, 2024)<\/p>\n","protected":false},"excerpt":{"rendered":"Com Marco Carola e PAWSA, Pacha e Destino Ibiza divulgam as opening parties do ver\u00e3o de 2024 em&hellip;","protected":false},"author":1,"featured_media":41919,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-41917","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mainstage","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pacha e Destino Ibiza anunciam festas de abertura de 2024<\/title>\n<meta name=\"description\" content=\"Com Marco Carola e PAWSA, Pacha e Destino Ibiza divulgam as opening parties do ver\u00e3o de 2024 em Ibiza, Espanha.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacha e Destino Ibiza anunciam festas de abertura de 2024\" \/>\n<meta property=\"og:description\" content=\"Com Marco Carola e PAWSA, Pacha e Destino Ibiza divulgam as opening parties do ver\u00e3o de 2024 em Ibiza, Espanha.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-21T17:07:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/4dbf95c5732c4cdf103571d9769155ae\"},\"headline\":\"Pacha e Destino Ibiza anunciam festas de abertura de 2024\",\"datePublished\":\"2024-02-21T17:07:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/\"},\"wordCount\":268,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Pacha.jpeg\",\"articleSection\":[\"Mainstage\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/\",\"name\":\"Pacha e Destino Ibiza anunciam festas de abertura de 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Pacha.jpeg\",\"datePublished\":\"2024-02-21T17:07:07+00:00\",\"description\":\"Com Marco Carola e PAWSA, Pacha e Destino Ibiza divulgam as opening parties do ver\u00e3o de 2024 em Ibiza, Espanha.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Pacha.jpeg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Pacha.jpeg\",\"width\":1280,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pacha e Destino Ibiza anunciam festas de abertura de 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/4dbf95c5732c4cdf103571d9769155ae\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pacha e Destino Ibiza anunciam festas de abertura de 2024","description":"Com Marco Carola e PAWSA, Pacha e Destino Ibiza divulgam as opening parties do ver\u00e3o de 2024 em Ibiza, Espanha.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/","og_locale":"pt_BR","og_type":"article","og_title":"Pacha e Destino Ibiza anunciam festas de abertura de 2024","og_description":"Com Marco Carola e PAWSA, Pacha e Destino Ibiza divulgam as opening parties do ver\u00e3o de 2024 em Ibiza, Espanha.","og_url":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/","og_site_name":"Beat for Beat","article_published_time":"2024-02-21T17:07:07+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/4dbf95c5732c4cdf103571d9769155ae"},"headline":"Pacha e Destino Ibiza anunciam festas de abertura de 2024","datePublished":"2024-02-21T17:07:07+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/"},"wordCount":268,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha.jpeg","articleSection":["Mainstage"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/","url":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/","name":"Pacha e Destino Ibiza anunciam festas de abertura de 2024","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha.jpeg","datePublished":"2024-02-21T17:07:07+00:00","description":"Com Marco Carola e PAWSA, Pacha e Destino Ibiza divulgam as opening parties do ver\u00e3o de 2024 em Ibiza, Espanha.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha.jpeg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/02\/Pacha.jpeg","width":1280,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/pacha-e-destino-ibiza-anunciam-festas-de-abertura-de-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Pacha e Destino Ibiza anunciam festas de abertura de 2024"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/4dbf95c5732c4cdf103571d9769155ae","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b7524c1a26a83cf0269d6f7d30f8ae4dacdf22f4b0dfbab347d4d651809fc48?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/beatforbeat.com.br\/site\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/41917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=41917"}],"version-history":[{"count":1,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/41917\/revisions"}],"predecessor-version":[{"id":41922,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/41917\/revisions\/41922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/41919"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=41917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=41917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=41917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}