{"id":43701,"date":"2024-05-01T17:40:42","date_gmt":"2024-05-01T20:40:42","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=43701"},"modified":"2024-05-01T17:40:42","modified_gmt":"2024-05-01T20:40:42","slug":"blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/","title":{"rendered":"Blugazer lan\u00e7a sua nova obra-prima &#8216;The Home Between My Walls&#8217;"},"content":{"rendered":"<p>Com melodias et\u00e9reas e sintetizadores cintilantes, Blugazer nos apresenta ao seu novo single, &#8216;The Home Between My Walls&#8217;. Escute agora.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-43702 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943.jpg\" alt=\"Blugazer\" width=\"630\" height=\"489\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943.jpg 1367w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943-300x233.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943-1024x795.jpg 1024w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943-768x596.jpg 768w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/489;\" \/><\/a><\/p>\n<p>O talentoso artista <strong>Blugazer<\/strong> nos convida a entrar em <em>&#8216;The Home Between My Walls&#8217;<\/em>, sua nova obra-prima que nos transporta para um universo sonoro imersivo e encantador. Atrav\u00e9s de uma produ\u00e7\u00e3o impec\u00e1vel e detalhada, Blugazer constr\u00f3i uma atmosfera vibrante e alegre, convidando-nos a explorar os cantos e recantos de sua mente criativa. Ou\u00e7a <a href=\"https:\/\/open.spotify.com\/track\/4vD9ZQetspxm71UUzjxXP6\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p><div id=\"beatf-1836102844\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p><em>&#8216;The Home Between My Walls&#8217;<\/em> \u00e9 mais do que apenas uma m\u00fasica, \u00e9 uma experi\u00eancia sensorial completa. As melodias et\u00e9reas e os sintetizadores cintilantes nos envolvem em um abra\u00e7o acolhedor, enquanto os ritmos pulsantes nos convidam a dan\u00e7ar e celebrar a beleza da vida. A produ\u00e7\u00e3o meticulosa de Blugazer \u00e9 evidente em cada detalhe, desde os samples cuidadosamente selecionados at\u00e9 os efeitos sonoros que d\u00e3o vida \u00e0 sua vis\u00e3o art\u00edstica.<\/p>\n<p>Nesta jornada musical, Blugazer nos presenteia com um refr\u00e3o contagiante que se repete em nossa mente como um mantra. As letras, embora simples, carregam uma mensagem profunda sobre o lar que encontramos dentro de n\u00f3s mesmos, um lugar de paz, seguran\u00e7a e amor incondicional.<\/p>\n<p><em>&#8216;The Home Between My Walls&#8217;<\/em> \u00e9 mais uma obra-prima da &#8220;f\u00e1brica de sonhos&#8221; de Blugazer, consolidando sua posi\u00e7\u00e3o como um dos artistas eletr\u00f4nicos mais talentosos e inovadores da atualidade. A m\u00fasica \u00e9 um convite para nos conectarmos com nossa ess\u00eancia, celebrar a beleza do mundo ao nosso redor e encontrar a paz interior que todos n\u00f3s buscamos.<\/p>\n<p>Escute:<\/p>\n<p><iframe title=\"Spotify Embed: The Home Between My Walls\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" data-src=\"https:\/\/open.spotify.com\/embed\/track\/4vD9ZQetspxm71UUzjxXP6?utm_source=oembed\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"Com melodias et\u00e9reas e sintetizadores cintilantes, Blugazer nos apresenta ao seu novo single, &#8216;The Home Between My Walls&#8217;.&hellip;","protected":false},"author":2,"featured_media":43702,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[7938],"tags":[18940,18941],"class_list":{"0":"post-43701","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-lancamentos","8":"tag-blugazer","9":"tag-the-home-between-my-walls","10":"cs-entry","11":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blugazer lan\u00e7a sua nova obra-prima &#039;The Home Between My Walls&#039;<\/title>\n<meta name=\"description\" content=\"Com melodias et\u00e9reas e sintetizadores cintilantes, Blugazer nos apresenta ao seu novo single, &#039;The Home Between My Walls&#039;. Escute agora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blugazer lan\u00e7a sua nova obra-prima &#039;The Home Between My Walls&#039;\" \/>\n<meta property=\"og:description\" content=\"Com melodias et\u00e9reas e sintetizadores cintilantes, Blugazer nos apresenta ao seu novo single, &#039;The Home Between My Walls&#039;. Escute agora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T20:40:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1367\" \/>\n\t<meta property=\"og:image:height\" content=\"1061\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"Blugazer lan\u00e7a sua nova obra-prima &#8216;The Home Between My Walls&#8217;\",\"datePublished\":\"2024-05-01T20:40:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/\"},\"wordCount\":283,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/press-shot-1608680349644-e1714596009943.jpg\",\"keywords\":[\"Blugazer\",\"The Home Between My Walls\"],\"articleSection\":[\"Lan\u00e7amentos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/\",\"name\":\"Blugazer lan\u00e7a sua nova obra-prima 'The Home Between My Walls'\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/press-shot-1608680349644-e1714596009943.jpg\",\"datePublished\":\"2024-05-01T20:40:42+00:00\",\"description\":\"Com melodias et\u00e9reas e sintetizadores cintilantes, Blugazer nos apresenta ao seu novo single, 'The Home Between My Walls'. Escute agora.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/press-shot-1608680349644-e1714596009943.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/press-shot-1608680349644-e1714596009943.jpg\",\"width\":1367,\"height\":1061,\"caption\":\"Blugazer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blugazer lan\u00e7a sua nova obra-prima &#8216;The Home Between My Walls&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blugazer lan\u00e7a sua nova obra-prima 'The Home Between My Walls'","description":"Com melodias et\u00e9reas e sintetizadores cintilantes, Blugazer nos apresenta ao seu novo single, 'The Home Between My Walls'. Escute agora.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/","og_locale":"pt_BR","og_type":"article","og_title":"Blugazer lan\u00e7a sua nova obra-prima 'The Home Between My Walls'","og_description":"Com melodias et\u00e9reas e sintetizadores cintilantes, Blugazer nos apresenta ao seu novo single, 'The Home Between My Walls'. Escute agora.","og_url":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2024-05-01T20:40:42+00:00","og_image":[{"width":1367,"height":1061,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943.jpg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"Blugazer lan\u00e7a sua nova obra-prima &#8216;The Home Between My Walls&#8217;","datePublished":"2024-05-01T20:40:42+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/"},"wordCount":283,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943.jpg","keywords":["Blugazer","The Home Between My Walls"],"articleSection":["Lan\u00e7amentos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/","url":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/","name":"Blugazer lan\u00e7a sua nova obra-prima 'The Home Between My Walls'","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943.jpg","datePublished":"2024-05-01T20:40:42+00:00","description":"Com melodias et\u00e9reas e sintetizadores cintilantes, Blugazer nos apresenta ao seu novo single, 'The Home Between My Walls'. Escute agora.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2024\/05\/press-shot-1608680349644-e1714596009943.jpg","width":1367,"height":1061,"caption":"Blugazer"},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/blugazer-lanca-sua-nova-obra-prima-the-home-between-my-walls\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Blugazer lan\u00e7a sua nova obra-prima &#8216;The Home Between My Walls&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/43701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=43701"}],"version-history":[{"count":1,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/43701\/revisions"}],"predecessor-version":[{"id":43703,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/43701\/revisions\/43703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/43702"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=43701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=43701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=43701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}