{"id":50572,"date":"2025-03-07T17:15:32","date_gmt":"2025-03-07T20:15:32","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=50572"},"modified":"2025-03-07T17:15:32","modified_gmt":"2025-03-07T20:15:32","slug":"rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/","title":{"rendered":"Rodney Dinkles e Artsychoke est\u00e3o juntos na track &#8216;Wait, What?&#8217;"},"content":{"rendered":"<p>Com batidas sincopadas e linhas de baixo intensas, Rodney Dinkles e Artsychoke est\u00e3o juntos em &#8216;Wait, What?&#8217; pela Quack Squawk Honk.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg\"><img decoding=\"async\" class=\"aligncenter wp-image-50573 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg\" alt=\"Rodney Dinkles\" width=\"630\" height=\"489\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg 524w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143-300x233.jpeg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143-332x258.jpeg 332w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/489;\" \/><\/a><\/p>\n<p><strong>Rodney Dinkles<\/strong> e <strong>Artsychoke<\/strong> uniram for\u00e7as para apresentar &#8216;<em>Wait, What?<\/em>&#8216;, uma faixa que mergulha nas profundezas da m\u00fasica eletr\u00f4nica, lan\u00e7ada pela gravadora <strong>Quack Squawk Honk<\/strong>. A m\u00fasica destaca-se por suas batidas sincopadas e linhas de baixo intensas, criando uma atmosfera envolvente que captura a ess\u00eancia do g\u00eanero. Ou\u00e7a <a href=\"https:\/\/open.spotify.com\/track\/6K69D4o6s8uf3QQYjbDgeT\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p><div id=\"beatf-3713759694\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p><em>&#8216;Wait, What?&#8217;<\/em> \u00e9 constru\u00edda sobre uma base r\u00edtmica que oscila entre BPMs, proporcionando uma sensa\u00e7\u00e3o de movimento constante. A estrutura da faixa incorpora pausas estrat\u00e9gicas, conhecidas como &#8220;bass drops&#8221;, onde a percuss\u00e3o cessa momentaneamente, retomando com ainda mais intensidade e introduzindo subgraves dominantes que ressoam profundamente. Essa din\u00e2mica mant\u00e9m o ouvinte em estado de expectativa e excita\u00e7\u00e3o.<\/p>\n<p>A produ\u00e7\u00e3o tamb\u00e9m se destaca pelo uso de &#8220;wobble bass&#8221;, uma t\u00e9cnica que manipula ritmicamente as frequ\u00eancias baixas, criando varia\u00e7\u00f5es que adicionam textura e profundidade \u00e0 composi\u00e7\u00e3o. Essa caracter\u00edstica, aliada a elementos percussivos espa\u00e7ados e samples cortados, resulta em uma sonoridade que \u00e9 ao mesmo tempo hipn\u00f3tica e energ\u00e9tica.<\/p>\n<p><em>&#8216;Wait, What?&#8217;<\/em> faz parte do EP &#8216;Fresh Cut Boi&#8217;, lan\u00e7ado recentemente pela Quack Squawk Honk, que inclui tamb\u00e9m um remix da faixa pela artista L3NA.<\/p>\n<p>Escute agora:<\/p>\n<p><iframe title=\"Spotify Embed: Wait, What?\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" data-src=\"https:\/\/open.spotify.com\/embed\/track\/6K69D4o6s8uf3QQYjbDgeT?utm_source=oembed\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"Com batidas sincopadas e linhas de baixo intensas, Rodney Dinkles e Artsychoke est\u00e3o juntos em &#8216;Wait, What?&#8217; pela&hellip;","protected":false},"author":2,"featured_media":50573,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[7938],"tags":[13653,22376,22377],"class_list":{"0":"post-50572","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-lancamentos","8":"tag-rodney-dinkles","9":"tag-wait","10":"tag-what","11":"cs-entry","12":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodney Dinkles e Artsychoke est\u00e3o juntos na track &#039;Wait, What?&#039;<\/title>\n<meta name=\"description\" content=\"Com batidas sincopadas e linhas de baixo intensas, Rodney Dinkles e Artsychoke est\u00e3o juntos em &#039;Wait, What?&#039; pela Quack Squawk Honk.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodney Dinkles e Artsychoke est\u00e3o juntos na track &#039;Wait, What?&#039;\" \/>\n<meta property=\"og:description\" content=\"Com batidas sincopadas e linhas de baixo intensas, Rodney Dinkles e Artsychoke est\u00e3o juntos em &#039;Wait, What?&#039; pela Quack Squawk Honk.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-07T20:15:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"524\" \/>\n\t<meta property=\"og:image:height\" content=\"407\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"Rodney Dinkles e Artsychoke est\u00e3o juntos na track &#8216;Wait, What?&#8217;\",\"datePublished\":\"2025-03-07T20:15:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg\",\"keywords\":[\"Rodney Dinkles\",\"Wait\",\"What?\"],\"articleSection\":[\"Lan\u00e7amentos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/\",\"name\":\"Rodney Dinkles e Artsychoke est\u00e3o juntos na track 'Wait, What?'\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg\",\"datePublished\":\"2025-03-07T20:15:32+00:00\",\"description\":\"Com batidas sincopadas e linhas de baixo intensas, Rodney Dinkles e Artsychoke est\u00e3o juntos em 'Wait, What?' pela Quack Squawk Honk.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg\",\"width\":524,\"height\":407,\"caption\":\"Rodney Dinkles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rodney Dinkles e Artsychoke est\u00e3o juntos na track &#8216;Wait, What?&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodney Dinkles e Artsychoke est\u00e3o juntos na track 'Wait, What?'","description":"Com batidas sincopadas e linhas de baixo intensas, Rodney Dinkles e Artsychoke est\u00e3o juntos em 'Wait, What?' pela Quack Squawk Honk.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/","og_locale":"pt_BR","og_type":"article","og_title":"Rodney Dinkles e Artsychoke est\u00e3o juntos na track 'Wait, What?'","og_description":"Com batidas sincopadas e linhas de baixo intensas, Rodney Dinkles e Artsychoke est\u00e3o juntos em 'Wait, What?' pela Quack Squawk Honk.","og_url":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2025-03-07T20:15:32+00:00","og_image":[{"width":524,"height":407,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"Rodney Dinkles e Artsychoke est\u00e3o juntos na track &#8216;Wait, What?&#8217;","datePublished":"2025-03-07T20:15:32+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/"},"wordCount":252,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg","keywords":["Rodney Dinkles","Wait","What?"],"articleSection":["Lan\u00e7amentos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/","url":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/","name":"Rodney Dinkles e Artsychoke est\u00e3o juntos na track 'Wait, What?'","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg","datePublished":"2025-03-07T20:15:32+00:00","description":"Com batidas sincopadas e linhas de baixo intensas, Rodney Dinkles e Artsychoke est\u00e3o juntos em 'Wait, What?' pela Quack Squawk Honk.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/03\/ab6761610000e5ebe48d7497e6e9143609479921-e1741378502143.jpeg","width":524,"height":407,"caption":"Rodney Dinkles"},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/rodney-dinkles-e-artsychoke-estao-juntos-na-track-wait-what\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Rodney Dinkles e Artsychoke est\u00e3o juntos na track &#8216;Wait, What?&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/50572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=50572"}],"version-history":[{"count":1,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/50572\/revisions"}],"predecessor-version":[{"id":50574,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/50572\/revisions\/50574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/50573"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=50572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=50572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=50572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}