{"id":52821,"date":"2025-07-02T16:26:51","date_gmt":"2025-07-02T19:26:51","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=52821"},"modified":"2025-07-02T16:26:51","modified_gmt":"2025-07-02T19:26:51","slug":"vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/","title":{"rendered":"Vincenzo Pizzi e Mary Gehnyei causam impacto em &#8216;POWER&#8217;"},"content":{"rendered":"<p>Feita para colidir com o corpo e ecoar na mente, \u2018POWER\u2019, de Vincenzo Pizzi em colabora\u00e7\u00e3o com Mary Gehnyei, \u00e9 intensidade em estado puro.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg\"><img decoding=\"async\" class=\"aligncenter wp-image-52822 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg\" alt=\"Vincenzo Pizzi\" width=\"630\" height=\"505\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg 640w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379-300x240.jpeg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379-332x266.jpeg 332w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 630px; --smush-placeholder-aspect-ratio: 630\/505;\" \/><\/a><\/p>\n<p><em>\u2018POWER\u2019,<\/em> de <strong>Vincenzo Pizzi<\/strong>, conduz uma experi\u00eancia densa e f\u00edsica. A base \u00e9 r\u00edgida, repleta de texturas saturadas e batidas que n\u00e3o d\u00e3o tr\u00e9gua. No centro desse v\u00f3rtice r\u00edtmico, a voz de <strong>Mary Gehnyei<\/strong> surge como um feiti\u00e7o industrial \u2014 mantralizada, repetitiva, evocativa. Ela n\u00e3o canta, ela invoca. E entre camadas \u00e1cidas e timbres corro\u00eddos, cada palavra reverbera como comando. Ou\u00e7a <a href=\"https:\/\/open.spotify.com\/intl-it\/track\/30Z8PDsdrJCDzT6csCITcK\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p><div id=\"beatf-959676816\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>A constru\u00e7\u00e3o da faixa n\u00e3o oferece respiro. Vincenzo trabalha com som bruto e direto, desdobrando a energia do techno em formas que parecem funcionar mais como impacto do que como melodia. A estrutura se mant\u00e9m tensa e hipn\u00f3tica, guiada por linhas que ardem e por frequ\u00eancias que vibram dentro da pele. A presen\u00e7a da voz feminina n\u00e3o suaviza: ela intensifica \u2014 \u00e9 um chamado, n\u00e3o um al\u00edvio.<\/p>\n<p><em>\u2018POWER\u2019<\/em> \u00e9 um manifesto sonoro. Uma faixa que transforma pista em rito, som em impacto e repeti\u00e7\u00e3o em transe. H\u00e1 algo de quase xam\u00e2nico na forma como tudo se repete com varia\u00e7\u00f5es m\u00ednimas, mas suficientes para manter o corpo em alerta constante. A for\u00e7a est\u00e1 na insist\u00eancia. E a insist\u00eancia, no controle absoluto da tens\u00e3o.<\/p>\n<p>\u00c9 techno em sua forma mais crua e ritual\u00edstica \u2014 feito n\u00e3o apenas para tocar, mas para dominar.<\/p>\n<p>Escute:<\/p>\n<p><iframe title=\"Spotify Embed: POWER - Original Mix\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" data-src=\"https:\/\/open.spotify.com\/embed\/track\/30Z8PDsdrJCDzT6csCITcK?utm_source=oembed\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"Feita para colidir com o corpo e ecoar na mente, \u2018POWER\u2019, de Vincenzo Pizzi em colabora\u00e7\u00e3o com Mary&hellip;","protected":false},"author":2,"featured_media":52822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[7938],"tags":[1108,23503],"class_list":["post-52821","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lancamentos","tag-power","tag-vincenzo-pizzi","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vincenzo Pizzi e Mary Gehnyei causam impacto em &#039;POWER&#039;<\/title>\n<meta name=\"description\" content=\"Feita para colidir com o corpo e ecoar na mente, \u2018POWER\u2019, de Vincenzo Pizzi em colabora\u00e7\u00e3o com Mary Gehnyei, \u00e9 intensidade em estado puro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vincenzo Pizzi e Mary Gehnyei causam impacto em &#039;POWER&#039;\" \/>\n<meta property=\"og:description\" content=\"Feita para colidir com o corpo e ecoar na mente, \u2018POWER\u2019, de Vincenzo Pizzi em colabora\u00e7\u00e3o com Mary Gehnyei, \u00e9 intensidade em estado puro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-02T19:26:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"Vincenzo Pizzi e Mary Gehnyei causam impacto em &#8216;POWER&#8217;\",\"datePublished\":\"2025-07-02T19:26:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/\"},\"wordCount\":269,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg\",\"keywords\":[\"Power\",\"Vincenzo Pizzi\"],\"articleSection\":[\"Lan\u00e7amentos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/\",\"name\":\"Vincenzo Pizzi e Mary Gehnyei causam impacto em 'POWER'\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg\",\"datePublished\":\"2025-07-02T19:26:51+00:00\",\"description\":\"Feita para colidir com o corpo e ecoar na mente, \u2018POWER\u2019, de Vincenzo Pizzi em colabora\u00e7\u00e3o com Mary Gehnyei, \u00e9 intensidade em estado puro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg\",\"width\":640,\"height\":513,\"caption\":\"Vincenzo Pizzi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vincenzo Pizzi e Mary Gehnyei causam impacto em &#8216;POWER&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vincenzo Pizzi e Mary Gehnyei causam impacto em 'POWER'","description":"Feita para colidir com o corpo e ecoar na mente, \u2018POWER\u2019, de Vincenzo Pizzi em colabora\u00e7\u00e3o com Mary Gehnyei, \u00e9 intensidade em estado puro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/","og_locale":"pt_BR","og_type":"article","og_title":"Vincenzo Pizzi e Mary Gehnyei causam impacto em 'POWER'","og_description":"Feita para colidir com o corpo e ecoar na mente, \u2018POWER\u2019, de Vincenzo Pizzi em colabora\u00e7\u00e3o com Mary Gehnyei, \u00e9 intensidade em estado puro.","og_url":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2025-07-02T19:26:51+00:00","og_image":[{"width":640,"height":513,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"Vincenzo Pizzi e Mary Gehnyei causam impacto em &#8216;POWER&#8217;","datePublished":"2025-07-02T19:26:51+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/"},"wordCount":269,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg","keywords":["Power","Vincenzo Pizzi"],"articleSection":["Lan\u00e7amentos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/","url":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/","name":"Vincenzo Pizzi e Mary Gehnyei causam impacto em 'POWER'","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg","datePublished":"2025-07-02T19:26:51+00:00","description":"Feita para colidir com o corpo e ecoar na mente, \u2018POWER\u2019, de Vincenzo Pizzi em colabora\u00e7\u00e3o com Mary Gehnyei, \u00e9 intensidade em estado puro.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Vincenzo-Pizzi-POWER-e1751484368379.jpeg","width":640,"height":513,"caption":"Vincenzo Pizzi"},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/vincenzo-pizzi-e-mary-gehnyei-causam-impacto-em-power\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Vincenzo Pizzi e Mary Gehnyei causam impacto em &#8216;POWER&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/52821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=52821"}],"version-history":[{"count":1,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/52821\/revisions"}],"predecessor-version":[{"id":52823,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/52821\/revisions\/52823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/52822"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=52821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=52821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=52821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}