{"id":53073,"date":"2025-07-21T14:59:23","date_gmt":"2025-07-21T17:59:23","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=53073"},"modified":"2025-07-21T14:59:23","modified_gmt":"2025-07-21T17:59:23","slug":"aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/","title":{"rendered":"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records"},"content":{"rendered":"<p>Choques sincronizados, graves industrializados e giros inesperados definem \u2018Tippy\u202fToe\u2019, nova faixa de AYCH. Escute agora.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-53067 size-full lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg\" alt=\"AYCH\" width=\"640\" height=\"461\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg 640w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670-300x216.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670-332x239.jpg 332w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/461;\" \/><\/a><\/p>\n<p>Em \u2018<em>Tippy\u202fToe\u2019<\/em>, AYCH imprime uma pegada implac\u00e1vel, onde a batida segue um percurso nervoso, alternando entre energia controlada e explos\u00f5es sonoras. AYCH conduz a faixa como um passeio por um labirinto el\u00e9trico: linhas de baixo cintilantes e subgraves intensos s\u00e3o quebrados por timbres distorcidos que surgem como alertas \u2014 uma tentativa de equil\u00edbrio entre t\u00e9cnica e caos calibrado. Ou\u00e7a <a href=\"https:\/\/open.spotify.com\/intl-pt\/album\/7f748eGWWFlahmtAWFLwy9?si=vRTwyvBxSGq7D8O9JZ7GcA\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p><div id=\"beatf-1675640199\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>O groove pulsa em camadas que se constroem por cortes estrat\u00e9gicos, com sintetizadores cortantes que provocam tens\u00e3o, acelerando o ritmo enquanto mant\u00eam a reten\u00e7\u00e3o. A densidade do som \u00e9 elevada, projetada para sistemas que respondem ao impacto f\u00edsico tanto quanto ao auditivo.<\/p>\n<p>A presen\u00e7a da marca de AYCH \u00e9 clara em cada virada \u2014 o uso de elementos abafados, stutters s\u00fabitos e reentradas explosivas assegura que a m\u00fasica respire mesmo num ambiente carregado de press\u00e3o. O som transita entre aggress\u00e3o s\u00f4nica e momentos que quase silenciam para depois romper com viol\u00eancia, refletindo uma est\u00e9tica que brinca com expectativa e quebra ritmo de forma calculada.<\/p>\n<p>Com estreia na colet\u00e2nea The Prophecy Volume 12, \u2018<em>Tippy\u202fToe<\/em>\u2019 reafirma a assinatura de AYCH como uma for\u00e7a imprevis\u00edvel e potente dentro do cat\u00e1logo da Bassrush Records \u2014 uma faixa feita para causar impacto, ainda que propositalmente intrincada, pronta para dominar pistas e sistemas de som robustos.<\/p>\n<p>Escute:<\/p>\n<p><iframe title=\"Spotify Embed: Tippy Toe\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" data-src=\"https:\/\/open.spotify.com\/embed\/album\/7f748eGWWFlahmtAWFLwy9?si=vRTwyvBxSGq7D8O9JZ7GcA&#038;utm_source=oembed\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"Choques sincronizados, graves industrializados e giros inesperados definem \u2018Tippy\u202fToe\u2019, nova faixa de AYCH. Escute agora. Em \u2018Tippy\u202fToe\u2019, AYCH&hellip;","protected":false},"author":2,"featured_media":53067,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[7938],"tags":[23605,23606],"class_list":{"0":"post-53073","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-lancamentos","8":"tag-aych","9":"tag-tippy-toe","10":"cs-entry","11":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records<\/title>\n<meta name=\"description\" content=\"Choques sincronizados, graves industrializados e giros inesperados definem \u2018Tippy\u202fToe\u2019, nova faixa de AYCH. Escute agora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records\" \/>\n<meta property=\"og:description\" content=\"Choques sincronizados, graves industrializados e giros inesperados definem \u2018Tippy\u202fToe\u2019, nova faixa de AYCH. Escute agora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-21T17:59:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"461\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records\",\"datePublished\":\"2025-07-21T17:59:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/\"},\"wordCount\":271,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg\",\"keywords\":[\"AYCH\",\"Tippy\u202fToe\"],\"articleSection\":[\"Lan\u00e7amentos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/\",\"name\":\"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg\",\"datePublished\":\"2025-07-21T17:59:23+00:00\",\"description\":\"Choques sincronizados, graves industrializados e giros inesperados definem \u2018Tippy\u202fToe\u2019, nova faixa de AYCH. Escute agora.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg\",\"width\":640,\"height\":461,\"caption\":\"Green Matter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records","description":"Choques sincronizados, graves industrializados e giros inesperados definem \u2018Tippy\u202fToe\u2019, nova faixa de AYCH. Escute agora.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/","og_locale":"pt_BR","og_type":"article","og_title":"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records","og_description":"Choques sincronizados, graves industrializados e giros inesperados definem \u2018Tippy\u202fToe\u2019, nova faixa de AYCH. Escute agora.","og_url":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2025-07-21T17:59:23+00:00","og_image":[{"width":640,"height":461,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records","datePublished":"2025-07-21T17:59:23+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/"},"wordCount":271,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg","keywords":["AYCH","Tippy\u202fToe"],"articleSection":["Lan\u00e7amentos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/","url":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/","name":"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg","datePublished":"2025-07-21T17:59:23+00:00","description":"Choques sincronizados, graves industrializados e giros inesperados definem \u2018Tippy\u202fToe\u2019, nova faixa de AYCH. Escute agora.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/07\/Green-Matter-Weekender-feat.-Nat-James-e1753120094670.jpg","width":640,"height":461,"caption":"Green Matter"},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/aych-apresenta-o-novo-single-tippy-toe-pela-bassrush-records\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"AYCH apresenta o novo single \u2018Tippy\u202fToe\u2019 pela Bassrush Records"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/53073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=53073"}],"version-history":[{"count":1,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/53073\/revisions"}],"predecessor-version":[{"id":53074,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/53073\/revisions\/53074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/53067"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=53073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=53073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=53073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}