{"id":53580,"date":"2025-08-22T11:09:27","date_gmt":"2025-08-22T14:09:27","guid":{"rendered":"https:\/\/beatforbeat.com.br\/site\/?p=53580"},"modified":"2025-08-22T11:09:27","modified_gmt":"2025-08-22T14:09:27","slug":"trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records","status":"publish","type":"post","link":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/","title":{"rendered":"Trance Wax lan\u00e7a o single &#8216;Hold On 2 U&#8217; pela Dreamstate Records"},"content":{"rendered":"<p>Trance Wax lan\u00e7a a nova faixa &#8216;Hold On 2 U&#8217;, pela Dreamstate Records \u2014 um mergulho emocional no trance moderno. Escute agora.<\/p>\n<p><a href=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-53581 lazyload\" data-src=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg\" alt=\"Trance Wax\" width=\"640\" height=\"448\" data-srcset=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg 640w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175-300x210.jpg 300w, https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175-332x232.jpg 332w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/448;\" \/><\/a><\/p>\n<p><strong>Trance Wax<\/strong> apresenta \u2018<em>Hold On 2 U<\/em>\u2019 como segundo single de seu rec\u00e9m-lan\u00e7ado EP pela <strong>Dreamstate Records<\/strong>, uma pe\u00e7a cheia de alma que flui como um sopro mel\u00f3dico projetado para conectar, suspender e libertar. Ou\u00e7a <a href=\"https:\/\/open.spotify.com\/track\/7c5J56lb8VWlXN5XpFOCfC\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p><div id=\"beatf-1920514920\" class=\"beatf-conteudo_2 beatf-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5262797664076819\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-5262797664076819\" \ndata-ad-slot=\"8185743757\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>A produ\u00e7\u00e3o se ergue com uma percuss\u00e3o suspensa, cadenciada como respira\u00e7\u00e3o profunda, sobre a qual emergem linhas de voz repletas de sensibilidade e texturas c\u00e1lidas. A faixa se desdobra como um abra\u00e7o sonoro: melodias que se desenrolam com naturalidade, evoluindo em camadas sobreposta de nostalgia e luz emocional. H\u00e1 um senso claro de abertura: cada nota parece insinuar um espa\u00e7o maior, um lugar onde tudo pode se recompor.<\/p>\n<p><em>\u2018Hold On 2 U\u2019<\/em> vive nesse limiar entre introspec\u00e7\u00e3o e movimento; n\u00e3o peca pelo drama, mas brilha pela pureza de seu desenho emocional. A delicadeza r\u00edtmica e o calor anal\u00f3gico criam uma pista invis\u00edvel \u2014 aquela que busca dissolver a dist\u00e2ncia entre a mem\u00f3ria e o presente. Trance Wax mostra aqui sua capacidade de traduzir sentimentos profundos em paisagens sonoras que se tornam quase palp\u00e1veis.<\/p>\n<p>A faixa refor\u00e7a a vis\u00e3o do artista: criar m\u00fasica que n\u00e3o apenas se ouve, mas que se sente \u2014 fluida, aberta e profundamente honesta.<\/p>\n<p>Escute:<\/p>\n<p><iframe title=\"Spotify Embed: Hold On 2 U\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" data-src=\"https:\/\/open.spotify.com\/embed\/track\/7c5J56lb8VWlXN5XpFOCfC?utm_source=oembed\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"Trance Wax lan\u00e7a a nova faixa &#8216;Hold On 2 U&#8217;, pela Dreamstate Records \u2014 um mergulho emocional no&hellip;","protected":false},"author":2,"featured_media":53581,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[7938],"tags":[23831,22848],"class_list":{"0":"post-53580","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-lancamentos","8":"tag-hold-on-2-u","9":"tag-trance-wax","10":"cs-entry","11":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trance Wax lan\u00e7a o single &#039;Hold On 2 U&#039; pela Dreamstate Records<\/title>\n<meta name=\"description\" content=\"Trance Wax lan\u00e7a a nova faixa &#039;Hold On 2 U&#039;, pela Dreamstate Records \u2014 um mergulho emocional no trance moderno. Escute agora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trance Wax lan\u00e7a o single &#039;Hold On 2 U&#039; pela Dreamstate Records\" \/>\n<meta property=\"og:description\" content=\"Trance Wax lan\u00e7a a nova faixa &#039;Hold On 2 U&#039;, pela Dreamstate Records \u2014 um mergulho emocional no trance moderno. Escute agora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/\" \/>\n<meta property=\"og:site_name\" content=\"Beat for Beat\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/viktoraphael\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-22T14:09:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Raphael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@djviktorraphael\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Raphael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/\"},\"author\":{\"name\":\"Viktor Raphael\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\"},\"headline\":\"Trance Wax lan\u00e7a o single &#8216;Hold On 2 U&#8217; pela Dreamstate Records\",\"datePublished\":\"2025-08-22T14:09:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/\"},\"wordCount\":256,\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg\",\"keywords\":[\"Hold On 2 U\",\"Trance Wax\"],\"articleSection\":[\"Lan\u00e7amentos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/\",\"name\":\"Trance Wax lan\u00e7a o single 'Hold On 2 U' pela Dreamstate Records\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg\",\"datePublished\":\"2025-08-22T14:09:27+00:00\",\"description\":\"Trance Wax lan\u00e7a a nova faixa 'Hold On 2 U', pela Dreamstate Records \u2014 um mergulho emocional no trance moderno. Escute agora.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg\",\"width\":640,\"height\":448,\"caption\":\"Trance Wax\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trance Wax lan\u00e7a o single &#8216;Hold On 2 U&#8217; pela Dreamstate Records\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"name\":\"Beat for Beat\",\"description\":\"M\u00fasica \u00e9 a Resposta\",\"publisher\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#organization\",\"name\":\"Beat for Beat\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"contentUrl\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Site-600@2x.png\",\"width\":1200,\"height\":1200,\"caption\":\"Beat for Beat\"},\"image\":{\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/#\\\/schema\\\/person\\\/561e4cc997e993fd5dd84e6b5c9dc306\",\"name\":\"Viktor Raphael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g\",\"caption\":\"Viktor Raphael\"},\"description\":\"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viktoraphael\",\"https:\\\/\\\/www.instagram.com\\\/vicraphael_\\\/\",\"https:\\\/\\\/x.com\\\/djviktorraphael\"],\"url\":\"https:\\\/\\\/beatforbeat.com.br\\\/site\\\/author\\\/viktor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trance Wax lan\u00e7a o single 'Hold On 2 U' pela Dreamstate Records","description":"Trance Wax lan\u00e7a a nova faixa 'Hold On 2 U', pela Dreamstate Records \u2014 um mergulho emocional no trance moderno. Escute agora.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/","og_locale":"pt_BR","og_type":"article","og_title":"Trance Wax lan\u00e7a o single 'Hold On 2 U' pela Dreamstate Records","og_description":"Trance Wax lan\u00e7a a nova faixa 'Hold On 2 U', pela Dreamstate Records \u2014 um mergulho emocional no trance moderno. Escute agora.","og_url":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/","og_site_name":"Beat for Beat","article_author":"https:\/\/www.facebook.com\/viktoraphael","article_published_time":"2025-08-22T14:09:27+00:00","og_image":[{"width":640,"height":448,"url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg","type":"image\/jpeg"}],"author":"Viktor Raphael","twitter_card":"summary_large_image","twitter_creator":"@djviktorraphael","twitter_misc":{"Escrito por":"Viktor Raphael","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/#article","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/"},"author":{"name":"Viktor Raphael","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306"},"headline":"Trance Wax lan\u00e7a o single &#8216;Hold On 2 U&#8217; pela Dreamstate Records","datePublished":"2025-08-22T14:09:27+00:00","mainEntityOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/"},"wordCount":256,"publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg","keywords":["Hold On 2 U","Trance Wax"],"articleSection":["Lan\u00e7amentos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/","url":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/","name":"Trance Wax lan\u00e7a o single 'Hold On 2 U' pela Dreamstate Records","isPartOf":{"@id":"https:\/\/beatforbeat.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/#primaryimage"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/#primaryimage"},"thumbnailUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg","datePublished":"2025-08-22T14:09:27+00:00","description":"Trance Wax lan\u00e7a a nova faixa 'Hold On 2 U', pela Dreamstate Records \u2014 um mergulho emocional no trance moderno. Escute agora.","breadcrumb":{"@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/#primaryimage","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2025\/08\/Trance-Wax-Hold-On-2-U-e1755871725175.jpg","width":640,"height":448,"caption":"Trance Wax"},{"@type":"BreadcrumbList","@id":"https:\/\/beatforbeat.com.br\/site\/trance-wax-lanca-o-single-hold-on-2-u-pela-dreamstate-records\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/beatforbeat.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Trance Wax lan\u00e7a o single &#8216;Hold On 2 U&#8217; pela Dreamstate Records"}]},{"@type":"WebSite","@id":"https:\/\/beatforbeat.com.br\/site\/#website","url":"https:\/\/beatforbeat.com.br\/site\/","name":"Beat for Beat","description":"M\u00fasica \u00e9 a Resposta","publisher":{"@id":"https:\/\/beatforbeat.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beatforbeat.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beatforbeat.com.br\/site\/#organization","name":"Beat for Beat","url":"https:\/\/beatforbeat.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","contentUrl":"https:\/\/beatforbeat.com.br\/site\/wp-content\/uploads\/2020\/05\/Logo-Site-600@2x.png","width":1200,"height":1200,"caption":"Beat for Beat"},"image":{"@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beatforbeat.com.br\/site\/#\/schema\/person\/561e4cc997e993fd5dd84e6b5c9dc306","name":"Viktor Raphael","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6eade5aeded37bd5ee2c073682b2a295287aeb61ca43d85c06a0fa10b4bf7e9?s=96&d=mm&r=g","caption":"Viktor Raphael"},"description":"DJ, Produtor, Redator, Libriano e Sonhador. Trance para amar e Techno para dan\u00e7ar, com uma ta\u00e7a de Gin para acompanhar. Onde \u00e9 o after?","sameAs":["https:\/\/www.facebook.com\/viktoraphael","https:\/\/www.instagram.com\/vicraphael_\/","https:\/\/x.com\/djviktorraphael"],"url":"https:\/\/beatforbeat.com.br\/site\/author\/viktor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/53580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/comments?post=53580"}],"version-history":[{"count":1,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/53580\/revisions"}],"predecessor-version":[{"id":53582,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/posts\/53580\/revisions\/53582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media\/53581"}],"wp:attachment":[{"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/media?parent=53580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/categories?post=53580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beatforbeat.com.br\/site\/wp-json\/wp\/v2\/tags?post=53580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}